{"id":605,"date":"2013-02-07T16:53:21","date_gmt":"2013-02-07T15:53:21","guid":{"rendered":"http:\/\/www.neschle.de\/index.php\/au-aufschrei\/au-aufschrei-62\/"},"modified":"2020-06-18T15:38:09","modified_gmt":"2020-06-18T14:38:09","slug":"au-aufschrei-62","status":"publish","type":"post","link":"https:\/\/neschle.de\/index.php\/au-aufschrei\/au-aufschrei-62\/","title":{"rendered":"Au &hellip; Aufschrei 62"},"content":{"rendered":"<header>\n<h2 style=\"text-align: left;\"><strong><span style=\"color: #4f81bd\">Peer-Blog, Peer-Block und Peer-Bock<\/span><\/strong><\/h2>\n<p style=\"text-align: left;\"><strong>Plagiat durch Suffragetten! \u201eAufschrei\u201c wird gestohlen.<\/strong><\/p>\n<\/header>\n<p style=\"text-align: left;\">Wieder diese Ahnungslosigkeit, wieder dieses besondere ethische Gesp\u00fcr bei Peer Steinbr\u00fcck. \u201eIch kann daran nicht ansatzweise etwas Anr\u00fcchiges erkennen\u201c, sagte er laut Rheinischer Post vom 7. Februar 2013 zum Unterst\u00fctzer-Blog von Karl-Heinz Steink\u00fchler.<\/p>\n<p style=\"text-align: left;\">Soweit von der Front Stein-Br\u00fcck-K\u00fchler nur politische Block-Meinung f\u00fcr Peer gemacht wird, hat Peer zweifellos recht, auch wenn die Meinung des coolen Blogmachers Steink\u00fchler \u00fcber die Abgr\u00fcnde der Politik schon sehr bezeichnend ist. Wie hei\u00dft es da so lieb:<\/p>\n<p style=\"text-align: left;\"><!--more--><\/p>\n<p style=\"text-align: left;\"><em>\u201eDass viel krauses Zeug geschrieben und mit Schmutz geworfen wird, falsche Behauptungen aufgestellt werden und beleidigt wird, ist in der Politik \u00fcblich.&#8220;<\/em><\/p>\n<p style=\"text-align: left;\"><em>Und damit das auch ja so bleibt, haben f\u00fcnf \u201eherausragenden Unternehmerpers\u00f6nlichkeiten\u201c einen \u201ePeerblog.de\u201c gegr\u00fcndet und ihn gleich mal mit einem sechsstelligen Betrag ausgestattet.<\/em> Das sind auf jeden Fall \u00fcber 100.000 Euro, also mehr als f\u00fcnf Reden von Peer Steinbr\u00fcck. Nun sind diese angeblich \u201eherausragenden Unternehmerpers\u00f6nlichkeiten\u201c bis heute anonym. Doch jeder Leser wird sich erinnern, wie die SPD \u00fcber anonyme Parteispenden von CDU\/CSU oder FDP getobt hat und nach rigoroser Bestrafung gerufen hat.<\/p>\n<p style=\"text-align: left;\">Aber handelt es sich bei diesem Blog denn wirklich um eine Parteispende? Die Antwort ist sogar f\u00fcr eine \u201eherausragende Unternehmerpers\u00f6nlichkeit\u201c nachvollziehbar:<\/p>\n<p style=\"text-align: left;\">Das deutsche Steuerrecht kennt seit ewiger Zeit den \u201egeldwerten Vorteil\u201c. Aus dieser Sicht ist es egal, ob mir jemand 20.000 Euro gibt und ich kaufe davon ein Auto oder ob er mir f\u00fcr 20.000 Euro das Auto kauft, um mir dann dieses Auto zu schenken. Das gilt sogar dann, wenn ich mir selbst lieber ein anderes Auto gekauft h\u00e4tte. Es gen\u00fcgt, wenn ich es annehme. Dadurch identifiziere ich mich mit diesem Vorteil.<\/p>\n<p style=\"text-align: left;\">Nun ist die Identifikation von Peer Steinbr\u00fcck mit dem Peer-Blog von beiden Seiten aus ganz offensichtlich, sowohl von dessen Machern als auch von Peer Steinbr\u00fcck selbst. Stein-Br\u00fcck und \u2013K\u00fchler haben da keine zwei Meinungen. Daher m\u00fcsste f\u00fcr Spenden schon etwas anderes gelten als f\u00fcr die normale Einkommenserzielung, damit man hier nicht von einem \u201egeldwerten Vorteil\u201c sprechen k\u00f6nnte.<\/p>\n<p style=\"text-align: left;\">Sonst aber ist die Spende der herausragend unternehmerischen Peer-Fans f\u00fcr diesen Blog nichts anderes als ein \u201egeldwerter Vorteil\u201c f\u00fcr die SPD, von deren Spitzenkandidaten begr\u00fc\u00dft und offensichtlich f\u00fcr \u201evorteilhaft\u201c befunden. Den Betrag h\u00e4tten diese Unternehmer n\u00e4mlich auch der SPD direkt spenden k\u00f6nnen und die h\u00e4tte dann diesen aufwendigen Blog starten k\u00f6nnen.<\/p>\n<p style=\"text-align: left;\">In der Sache w\u00e4re dann faktisch alles gleich geblieben, aber es h\u00e4tten die Regeln f\u00fcr Parteispenden gegolten und die h\u00e4tten den anonymen Mummenschanz der SPD-Genossen um den Peer-Blog nicht zugelassen.<\/p>\n<p style=\"text-align: left;\">Die \u201eherausragenden Unternehmer\u201c h\u00e4tten das eigentlich wissen m\u00fcssen. Und schlie\u00dflich ist es gerade die SPD, die sich dagegen wehrt, dass es bei Parteispenden zugeht wie beim Karneval in Venedig. Nun ganz offensichtlich scheinheilig!<\/p>\n<p style=\"text-align: left;\">Denn da geht es nur um Regeln f\u00fcr die anderen. Die SPD und ihr Spitzenkandidat d\u00fcrfen sie umgehen, ohne ein F\u00fcnkchen Unrechtsbewusstsein. Und das hat man ja wohl nicht, wenn man wie Peer Steinbr\u00fcck an dieser Sache \u201enicht ansatzweise etwas Anr\u00fcchiges erkennen\u201c kann. Es gibt daher nur einen Weg Steinbr\u00fccks erneuten Bock dabei ungeschossen zu machen: Vielleicht hat Peer naiverweise nur die Meinungsmache gemeint und die Sache mit deren Finanzierung ganz einfach verdr\u00e4ngt.<\/p>\n<p style=\"text-align: left;\">Von ihm kennen wir das Verdr\u00e4ngen der Finanzen ja schon. Aber noch nicht von einem herausragenden Unternehmer, der mit steuerrechtlichen \u00dcbungen vertraut sein sollte. Der wei\u00df doch genau, dass er durch die Finanzierung eines solchen Blogs, anders als bei einer Spende, anonym bleiben kann und genau das offenbar auch will. Gerade wenn und weil er eine \u201eherausragende Unternehmerpers\u00f6nlichkeit\u201c ist. Sp\u00e4testens aber, wenn Peer Steinbr\u00fcck mal bei einem der f\u00fcnf Unternehmer auftaucht, um \u201ekostenlos\u201c einen 20.000 Euro-Vortrag zu halten, ist es keine Spende mehr, sondern verdeckte Einkommenserzielung und \u2013verwendung von Peer Steinbr\u00fcck selbst.<\/p>\n<p style=\"text-align: left;\">Doch Moment! Wir kennen diese f\u00fcnf Unterst\u00fctzer zwar, wenn sie wirklich \u201eherausragende Unternehmerpers\u00f6nlichkeiten\u201c sind, aber wir wissen nicht, wer sie sind. Da k\u00f6nnen wir noch nicht einmal sehen, ob der Peer z.B. vorher sch\u00f6n gef\u00e4llig war oder mit der sp\u00e4teren \u00dcbernahme eines P\u00f6stchens dann gef\u00e4lligst gef\u00e4llig wird. Genosse Schr\u00f6der hat es vorgemacht. Wie hie\u00df es da so sch\u00f6n: Genosse der Bosse? \u2013<\/p>\n<p style=\"text-align: left;\">Liebe SPD- Genossen: Wie kommt Ihr mit dem Widerspruch klar, dass Ihr die Schwarz \u2013Gelben so ganz pauschal der Wirtschaftsh\u00f6rigkeit verd\u00e4chtigt und bei Euch selbst die Schotten dichtmacht, wenn es sogar konkrete Anhaltspunkte gibt? Ist nat\u00fcrlich kein Widerspruch: F\u00fcr Euch soll nat\u00fcrlich nicht gelten, was Ihr von den anderen verlangt. Immer wieder gern, wie bei allen \u201eMoralisten\u201c!<\/p>\n<p style=\"text-align: left;\">Und Sie, mein lieber Herr Steinbr\u00fcck. Sie irren mal wieder und schie\u00dfen mit diesem Blog den n\u00e4chsten Bock: Die \u00d6ffentlichkeit hat ein Recht, Namen und Summen ihrer Unterst\u00fctzer zu erfahren, nach denselben Regeln wie sie f\u00fcr Parteispenden gelten, gerade wenn und weil sie Kanzler werden wollen. Da gibt es keine Extraw\u00fcrste, f\u00fcr keinen Stein, weder f\u00fcr Meier noch K\u00fchler noch Br\u00fcck. Neschle hofft und erwartet daher, dass der Lammers es richtet.<\/p>\n<p style=\"text-align: justify;\"><a title=\"PDF-Datei\" href=\"http:\/\/www.neschle.de\/download-manager.php?id=194\"><span style=\"font-size: small;\">PDF-Datei<\/span><\/a><\/p>\n<p style=\"text-align: justify;\">This post was downloaded by  1123 people until now.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Peer-Blog, Peer-Block und Peer-Bock Plagiat durch Suffragetten! \u201eAufschrei\u201c wird gestohlen. Wieder diese Ahnungslosigkeit, wieder dieses besondere ethische Gesp\u00fcr bei Peer Steinbr\u00fcck. \u201eIch kann daran nicht ansatzweise etwas Anr\u00fcchiges erkennen\u201c, sagte er laut Rheinischer Post vom 7. Februar 2013 zum Unterst\u00fctzer-Blog von Karl-Heinz Steink\u00fchler. Soweit von der Front Stein-Br\u00fcck-K\u00fchler nur politische Block-Meinung f\u00fcr Peer gemacht wird, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/neschle.de\/index.php\/au-aufschrei\/au-aufschrei-62\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eAu &hellip; Aufschrei 62\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,4],"tags":[14,60,11,21,23],"_links":{"self":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/605"}],"collection":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/comments?post=605"}],"version-history":[{"count":1,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/605\/revisions"}],"predecessor-version":[{"id":761,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/605\/revisions\/761"}],"wp:attachment":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/media?parent=605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/categories?post=605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/tags?post=605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}