{"id":60,"date":"2007-05-22T11:39:22","date_gmt":"2007-05-22T10:39:22","guid":{"rendered":"http:\/\/www.neschle.de\/wordpress\/?p=60"},"modified":"2020-06-19T20:53:41","modified_gmt":"2020-06-19T19:53:41","slug":"ko-witz-16","status":"publish","type":"post","link":"https:\/\/neschle.de\/index.php\/ulkereien\/ko-witz-16\/","title":{"rendered":"Ulkerei 16"},"content":{"rendered":"<header>\n<h2 style=\"text-align: left;\"><strong><span style=\"color: #4f81bd\">Bill Gates schwitzt zwar, klebt aber nicht. Bei Bill geht\u2019s!<\/span><\/strong><\/h2>\n<\/header>\n<p style=\"text-align: left;\">Endlich kommt Bill Gates zu der Ehre, die ihm aufgrund der Begl\u00fcckung dieser Welt mit seiner stets lernf\u00e4higen und verbesserungsw\u00fcrdigen Weichware l\u00e4ngst zuteil geworden sein haben m\u00fcsste.<!--more--> Sein Konterfei ist auf einer Briefmarke der amerikanischen Post zu sehen.<\/p>\n<p style=\"text-align: left;\">Allerdings h\u00e4ufen sich schon nach kurzer Zeit die Beschwerden, die Marke klebe nicht. Mit Unterst\u00fctzung durch Bill Gates selbst werden ber\u00fchmte Forscher mit der Untersuchung dieser verbl\u00fcffenden Tatsache beauftragt.<\/p>\n<p style=\"text-align: left;\">Die Forscher kommen zu dem Ergebnis: Die Marke klebt wie jede andere Marke auch. Es gibt keinerlei Beanstandung.<\/p>\n<p style=\"text-align: left;\">Eine zweite Untersuchung wird in Auftrag gegeben. Die Forscher beobachten die Verwendung der Marke. Und siehe das Geheimnis l\u00fcftet sich: Die Leute spucken auf die Vorderseite.<\/p>\n<p><a title=\"PDF-Datei\" href=\"http:\/\/www.neschle.de\/download-manager.php?id=43\">PDF-Datei<\/a><br \/>\nThis post was downloaded by  1361  people until now.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bill Gates schwitzt zwar, klebt aber nicht. Bei Bill geht\u2019s! Endlich kommt Bill Gates zu der Ehre, die ihm aufgrund der Begl\u00fcckung dieser Welt mit seiner stets lernf\u00e4higen und verbesserungsw\u00fcrdigen Weichware l\u00e4ngst zuteil geworden sein haben m\u00fcsste.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"_links":{"self":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/60"}],"collection":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/comments?post=60"}],"version-history":[{"count":1,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/60\/revisions"}],"predecessor-version":[{"id":927,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/60\/revisions\/927"}],"wp:attachment":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/media?parent=60"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/categories?post=60"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/tags?post=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}