{"id":54,"date":"2007-05-16T14:46:58","date_gmt":"2007-05-16T13:46:58","guid":{"rendered":"http:\/\/www.neschle.de\/wordpress\/?p=54"},"modified":"2020-06-21T15:57:34","modified_gmt":"2020-06-21T14:57:34","slug":"leon-neschle-14-21-woche-2007","status":"publish","type":"post","link":"https:\/\/neschle.de\/index.php\/blog\/leon-neschle-14-21-woche-2007\/","title":{"rendered":"Leon Neschle 14 (21. Woche 2007)"},"content":{"rendered":"<header>\n<h2 style=\"text-align: left;\"><strong><span style=\"color: #4f81bd\">Schlechter Staats-Rat! Der schafft Arbeit f\u00fcr einen!<\/span><\/strong><\/h2>\n<\/header>\n<p style=\"text-align: left;\"><em>Unverantwortlich ist, wenn Verantwortliche keine Sachkunde und Sachkundige keine Verantwortung haben.&nbsp;<\/em>(Arno S\u00f6ltner)<\/p>\n<p style=\"text-align: left;\"><i>Die Gesundheit ist ein zu wichtiges Gut, um es der Privatwirtschaft zu \u00fcberlassen.<\/i><a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a><i> <\/i>Welche Politikerin das gesagt hat, ist klar. Tut aber nichts zur Sache.<!--more--> Und um die geht es hier. Gesagt haben, k\u00f6nnten das viele. Genau so viele wie die, die so denken in diesem Land. Das ist wahrscheinlich die Mehrheit. Ob man das <i>Denken<\/i> nennen kann? Schaunwermal!<\/p>\n<h3 style=\"text-align: left;\"><strong>A. Kranken- und Hungerversicherung, Kranken- und Hungerh\u00e4user.<\/strong><\/h3>\n<p style=\"text-align: left;\">Die Ern\u00e4hrung ist ebenfalls ein sehr wichtiges Gut, vielleicht sogar wichtiger. Wer w\u00fcrde sich noch um seine Gesundheit k\u00fcmmern wollen, wenn er verdurstet oder verhungert w\u00e4re? Zum Gl\u00fcck hat die Versorgung mit Nahrungsmitteln immer recht gut funktioniert. Jedenfalls da, wo sie der Privatwirtschaft \u00fcberlassen war. Wo der Staat oder der \u00dcberstaat EG ein- und \u00fcbergreift, l\u00e4sst sich das nicht behaupten. \u00dcber die deutsche Politik ist da allerdings l\u00e4ngst der Stabreim gebrochen: <i>Br\u00fcsseler B\u00fcrokraten brauchen Berliner Bolidicker berhauptnichmehr<\/i>.<\/p>\n<p style=\"text-align: left;\">Treiben wir das obige Argument zur Gesundheitspolitik auf die Spitze: An der Bedeutung der Ern\u00e4hrung gemessen ist das Ern\u00e4hrungswesen in Deutschland bei weitem nicht genug verstaatlicht. Ja, im Reichsn\u00e4hrstand des Dritten Reichs oder in der DDR, da hatte das Ern\u00e4hrungswesen noch die richtige Bedeutung. \ud83d\ude09<\/p>\n<p style=\"text-align: left;\">Und wie k\u00f6nnte es in einem <i>Bundesn\u00e4hrstand<\/i> aussehen? Darin erhielte die Ern\u00e4hrung die ihr zustehende Bedeutung. Sie fiele nicht mehr dem unkontrollierten Dahinwursteln privater Bauern und sonstiger Lebensmittelproduzenten anheim. Falls der Bundesn\u00e4hrstand preu\u00dfisch-staatlich sauber organisiert w\u00e4re. Wie gelingt das? Ganz einfach: Wir m\u00fcssen nur alles \u00fcbertragen, was schon im staatlich organisierten Gesundheitswesen nicht klappt und wir erhalten das, was auch bei der Ern\u00e4hrung der DDR-Bev\u00f6lkerung schon damals nicht geklappt hat.<\/p>\n<p style=\"text-align: left;\">Zum Zwecke der gesicherten Ern\u00e4hrung sollten sich daher alle Staatsb\u00fcrger pflichtversichern. Sie sollten gezwungen werden, in eine Hungerkasse einzuzahlen, die im Falle erwiesener Hungerattacken die Hungerversicherungssumme auszahlen oder gleich Essen und Trinken austeilen w\u00fcrde. Nach Vorlage eines Hungerscheins nat\u00fcrlich. Und nach pflichtgem\u00e4\u00dfer Pr\u00fcfung wegen etwaiger Verst\u00f6\u00dfe gegen die Hungerversicherungsklauseln. \u00dcber die staatliche Kontrolle w\u00e4re dann gesichert, dass immer richtig gehungert wird und nicht irgendeiner blo\u00df \u201ehungerfeiert\u201c.<\/p>\n<p style=\"text-align: left;\">In krassen F\u00e4llen des Hungers und der grassierenden Magersucht w\u00fcrde \u00fcber einen Hungerbeauftragten in ein Hungerhaus eingewiesen, in dem der Versicherte zu Lasten der staatlichen Hungerversicherung wieder verdickt, ges\u00e4ttigt und entd\u00fcrstet w\u00fcrde. Betreutes Essen und Trinken unter Aufsicht w\u00e4ren selbstverst\u00e4ndlich hoher Standard. Wichtig ist nat\u00fcrlich die permanente staatliche Kontrolle.<\/p>\n<p style=\"text-align: left;\"><i>Wir haben sie doch satt: die Lebensmittelskandale mit Schadstoffen und Gammelfleisch, Schandstoffen und Kamelfleisch? Wenn der Bundesn\u00e4hrstand k\u00fcnftig das Fleischwesen in der Hand hat, wird man nichts mehr davon h\u00f6ren. Denn nat\u00fcrlich ist dann auch die Presse viel zu wichtig! Informationen sind ein viel zu wichtiges Gut, um sie der Privatwirtschaft zu \u00fcberlassen. Man denke nur an die Fehlinformationen, denen wir t\u00e4glich ausgesetzt sind. Die k\u00f6nnten Paniken ausl\u00f6sen. Diese Probleme w\u00e4ren wir mit einem Schlag los, wenn alle Informationen in staatlicher Hand w\u00e4ren. Nur noch richtige Informationen, auf die wir uns verlassen k\u00f6nnen, s\u00e4mtlich staatlich gepr\u00fcft! Wie Gesundheit und Lebensmittel. Das g\u00e4be Sicherheit an der Nachrichtenfront ebenso wie im staatlichen Ern\u00e4hrungs- und Gesundheitswesen<\/i>.<\/p>\n<p style=\"text-align: left;\">Sch\u00f6ne Neue Welt! Sch\u00f6ne alte DDR! Wahre Nachrichten des CIA!<\/p>\n<h3 style=\"text-align: left;\"><strong>B. Qualit\u00e4t und Fortschritt im Lipsi-Schritt: Staatstanz, weil der Tanz zu wichtig ist!<\/strong><\/h3>\n<p style=\"text-align: left;\">Wahrscheinlich steckte die <i>private<\/i> Presse hinter den Falschinformationen, die Bush dazu gef\u00fchrt haben, den Irak anzugreifen. Beim CIA k\u00e4me das <i>niemals<\/i> vor. Ein staatlicher und stattlicher Nachrichtendienst eben. Da sind alle Informationen <b>c<\/b>entral, <b>i<\/b>ntelligent und <b>a<\/b>gentengepr\u00fcft. Informationen sind eben viel zu wichtig, um sie \u00fcber die private Presse zu erlangen! Sie d\u00fcrfen nur in der Hand des Staates sein. <i>Erst da werden sie richtig, selbst wenn sie falsch sind. <\/i>Und Kranke werden gesund im staatlichen Gesundheitswesen, schlechtes Essen wird gut im Bundesn\u00e4hrstand!?<\/p>\n<p style=\"text-align: left;\">Oder hat jemand schon einmal von Gammelfleisch in Nordkorea geh\u00f6rt? Da h\u00f6rt man gegenw\u00e4rtig nur etwas von \u201eFortschritt\u201c und \u00fcberhaupt nichts mehr von \u201eFleisch\u201c, nur dass die Leute von demselben fallen. Oder in der DDR? Das Gammelfleisch wurde doch mit Paketen in den Westen geschickt. Zur Unterminierung des imperialistischen westdeutschen Bundesn\u00e4hrstandes. Kontaminierte Nahrungsmittel in der DDR? Die Giftgurke aus dem Spreewald, die Gammelwurst von R\u00fcgen? Niemals! Wirklich nicht! <i>Zumindest nicht, dass man es w\u00fcsste.<\/i> Die Gurken hat sogar Neschle gegessen (Siehe das Buch \u201eWill(l)der Osten!\u201c). Sehr gut! <i>Aber wer isst heutzutage noch Gurken, wo wir so viel wichtigere Probleme haben.<\/i> Eines ganz wichtiges ist der Tanz, der mit Musik.<\/p>\n<p style=\"text-align: left;\">In der DDR war die Tanzmusik selbstverst\u00e4ndlich zu wichtig, um sie Privaten zu \u00fcberlassen. Die Staatsf\u00fchrung hat in Leipzig (lat. Lipsiens) den Lipsi entwickeln und sp\u00e4ter patentieren lassen. Jawohl! Gegen die perversen, unpatenten und drittklassigen Privatentwicklungen des Westens, Twist und Rock \u2019n\u2019 Roll, von denen man danach zum Gl\u00fcck nie wieder etwas h\u00f6rte. Umso mehr nat\u00fcrlich vom Lipsi, den heute jeder kennt.<\/p>\n<p style=\"text-align: left;\">Der w\u00fcste Beckenschwenker <i>Elvis the Pelvis<\/i> hatte mit seinem Presley-H\u00fcftschwung den Unterleib des jungen Werkt\u00e4tigennachwuchses ins Schwanken gebracht und mit ihm die Moralvorstellungen des regierenden Rentnerclubs. Davon musste man dem Nachwuchs abhelfen. Wegen der gro\u00dfen Internationalit\u00e4t der DDR machten Ulbricht, der kleine Che Guevara, und seine Mannschaft eine Anleihe beim <i>revolution\u00e4ren<\/i> <i>Tanz <\/i>S\u00fcdamerikas. Dazu mischte man geh\u00f6rige Prisen sozia-listiger deutscher Biederkeit. Fertig war die Tanzrevolution, an der die Welt genesen sollte. Im Taumel des staatsverordneten Fortschrittglaubens erlagen alle DDR-Kulturpolitiker dem Lipsi-Tanzschrittwahn. Hier zeigte sich wieder die \u00dcberlegenheit des Sozialmuses.<\/p>\n<p style=\"text-align: left;\">Die Staatsf\u00fchrung verglaubte sich sogar an die Weltsensation. Der Lipsi war f\u00fcr sie von so hoher Importanz, dass er <i>Exporttanz<\/i>(!) werden sollte. Er werde in den USA den Durchbruch schaffen!!! Das hatten sich die Gehirne staatlicher Organe im Osten wirklich zusammengebraut und von ihrem geistigen Gebr\u00e4u waren sie schon immer \u00fcberzeugt. Sie lie\u00dfen eine Helga Brauer den Lipsi besingen: <i>Heute tanzen alle jungen Leute im Lipsi-Schritt, nur noch im Lipsi-Schritt. Allen hat der Tanz sofort gefallen. Sie tanzen mit im Lipsi-Schritt.<\/i> &#8211; Eine wirklich tolle Musik f\u00fcr jeden, der nicht wei\u00df, was das ist.<\/p>\n<p style=\"text-align: left;\">Mit dem Lipsi-Schritt gegen den H\u00fcftschwung von Elvis. Das Dumme war nur: Die unverst\u00e4ndige Jugend wollte den Lipsi nicht wollen. Sie war nicht be-, sie war entgeistert. Das hatte die Partei nicht m\u00f6gen gemocht. Sie hatte da halt das falsche Volk und die falsche Jugend.<\/p>\n<p style=\"text-align: left;\">Den Tanz dem privaten Geschmack des Volkes zu \u00fcberlassen, wo der so wichtig ist, das w\u00e4re falsch gewesen. Eben! Daher gilt auch: Das Gesundheitswesen ist so wichtig, dass es der Staat \u00fcbernehmen muss und es nicht den Privaten \u00fcberlassen kann. Alles in staatliche H\u00e4nde! Lipsi-Schritt f\u00fcr Lipsi-Schritt. Meinen Lipsi lob ich mir!<\/p>\n<h3 style=\"text-align: left;\"><strong>C. Wir trauen dem Staat alles, Beamten nichts zu! Oder umgekehrt?<\/strong><\/h3>\n<p style=\"text-align: left;\">Aber Moment! Ist das nicht staatliche Wichtigtuerei? Die Privaten, denen man nichts mehr \u00fcberlassen will, das sind wir. Wir alle! Warum vertraut man uns nicht? Ach ja, Lenins Kontrolle ist besser! <i>Wenn man uns nicht traut, warum l\u00e4sst man einzelne von uns alles kontrollieren, wenn sie staatliche Funktionen haben. Wir sind zwar das Volk, aber die sind dann der Staat!<\/i><\/p>\n<p style=\"text-align: left;\"><i>Warum richtet sich das Misstrauen gegen den Menschen in Deutschland meist nur gegen ihn als privat wirtschaftendes Individuum oder schlimmer noch als Mitglied eines Gro\u00dfkonzerns? Warum nicht gegen den Menschen als Mitglied einer fast allm\u00e4chtigen Regierung oder staatlichen Verwaltung?<\/i> Eine solche Regierung bekommt man, wenn man alles verstaatlicht, was irgendwer f\u00fcr wichtig h\u00e4lt. Beamten trauen wir Deutschen doch sonst nichts zu, halten sie f\u00fcr faul und dumm.<\/p>\n<p style=\"text-align: left;\">Doch Beamten ist alles zuzutrauen! Geben wir ihnen nur die richtigen Kontrollinstrumente in die Hand: Sie werden ein Marionetten-Theater mit uns aufziehen. In der Steuerverwaltung und anderswo. Schauen wir uns an, was die im Lipsi-Schritt fortschreitende Verstaatlichung des Gesundheitswesens gebracht hat: Unzufriedene und demotivierte \u00c4rzte bei schlechteren Leistungen. Die werden immer zickiger, weil sie immer weniger Bock haben. Bei ihren Fehlern haben die \u00c4rzte freilich den Vorteil, dass schnell Gras dar\u00fcber w\u00e4chst. &#8211;<\/p>\n<p style=\"text-align: left;\">In der betriebswirtschaftlichen Personalf\u00fchrungslehre w\u00fcrde man von <i>Impoverished Management<\/i> sprechen. Die \u00c4rzte zeigen fortan <i>weder Lust noch Leistung<\/i>. Impoverished, also verarmt, vor allem was ihren Willen und ihr Engagement angeht. <i>\u00c4rzte verwalten heute ein zur Staatssache erkl\u00e4rtes, weil viel zu bedeutsames Gesundheitsproblem. <u>Das Problem ist so wichtig f\u00fcr den Staat, dass es mittlerweile fast nicht mehr wichtig ist f\u00fcr den Arzt.<\/u><\/i> Der behandelt das Gesundheitsproblem und den Patienten nicht mehr verantwortlich und darum nicht mehr engagiert, au\u00dfer in England, fr\u00fcher oft von deutschen Politikern f\u00fcr sein Gesundheitssystem gescholten, wo er sich mittlerweile ein Mehrfaches hinzuverdienen kann. Und warum? Weil England kaum mehr \u00c4rzte hat. Die sind in den USA und von unten wachsen keine nach. Und in Deutschland? Da brauchen wir schon kaum mehr warten, bis die \u00c4rzte aus Tschechien, Polen oder Ungarn hier das Regiment \u00fcbernehmen.<\/p>\n<p style=\"text-align: left;\">Das Ganze l\u00e4uft unter dem politischen Banner der Effizienz im Gesundheitswesen. Wenn der Staat etwas macht, ist <i>Effizienz <\/i>oder<i> Fortschritt<\/i> <i><u>verbal<\/u><\/i> immer im Spiel, faktisch eher selten. Hat man je aus den Verlautbarungen der DDR-Staatsf\u00fchrung geh\u00f6rt, dass es nicht bergauf ging und nicht effizienter wurde? Das w\u00e4re der Gipfel gewesen. Doch da kam man nie an. Es musste ja weiter bergauf gehen!<\/p>\n<p style=\"text-align: left;\"><i>Die Gestaltungsfreude der staatlichen Macher ist den Freunden der Lipsi-Schritte wichtiger als die Gestaltungsfreude der Staatsb\u00fcrger. Diese B\u00fcrger kann man dann tausendmal auffordern, mehr zu tun und mehr zu rennen. Sie werden es nicht tun, weil es nicht mehr <u>ihre<\/u> Sache ist, und sie werden es nicht k\u00f6nnen, weil man ihnen die Luft zum Atmen und den Raum zum Leben nimmt. Legebatteriehaltung! Die sollen nun sogar mehr Freude an ihrer Entwicklung und der Entwicklung ihrer Umwelt haben. Und ein Ei des Kolumbus nach dem anderen legen. Aber warum nur? <\/i><\/p>\n<p style=\"text-align: left;\">Den DDR-Oberen hat es doch auch schon gereicht, den Fortschritt t\u00e4glich zu <i>verk\u00fcnden<\/i>. Aber den staatlichen Lipsi tanzt man eben auf der Stelle!<\/p>\n<p style=\"text-align: center;\">Was wichtig f\u00fcr uns alle w\u00e4re,<\/p>\n<p style=\"text-align: center;\">stets in des Staates Hand geh\u00f6re.<\/p>\n<p style=\"text-align: center;\">so reden viele hierzulande,<\/p>\n<p style=\"text-align: center;\">trotz der Beamten \u201efauler Bande\u201c!<\/p>\n<p style=\"text-align: center;\">Doch damit sind wir in der Falle:<\/p>\n<p style=\"text-align: center;\">Aus mit der Freiheit f\u00fcr uns alle!<\/p>\n<p style=\"text-align: center;\">(Version f\u00fcrs Ruhrgebiet: Aus mitti Freiheit von uns alle!)<\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\">\n<p style=\"text-align: left;\"><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Diesen Hinweis und die nachfolgende Idee verdankt Neschle einem ungew\u00f6hnlich schlanken Freund Er nennt ihn mal den \u201ePrintenk\u00f6nig\u201c. Danke daf\u00fcr! Viel Spa\u00df! Sapienti sat!<\/p>\n<p><a title=\"PDF-Datei\" href=\"http:\/\/www.neschle.de\/download-manager.php?id=11\">PDF-Datei<\/a><br \/>\nThis post was downloaded by  1245  people until now.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schlechter Staats-Rat! Der schafft Arbeit f\u00fcr einen! Unverantwortlich ist, wenn Verantwortliche keine Sachkunde und Sachkundige keine Verantwortung haben.&nbsp;(Arno S\u00f6ltner) Die Gesundheit ist ein zu wichtiges Gut, um es der Privatwirtschaft zu \u00fcberlassen.[1] Welche Politikerin das gesagt hat, ist klar. Tut aber nichts zur Sache.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,6],"tags":[14,11,21],"_links":{"self":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/54"}],"collection":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/comments?post=54"}],"version-history":[{"count":1,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/54\/revisions"}],"predecessor-version":[{"id":1051,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/54\/revisions\/1051"}],"wp:attachment":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/media?parent=54"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/categories?post=54"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/tags?post=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}