{"id":382,"date":"2009-02-10T13:37:00","date_gmt":"2009-02-10T12:37:00","guid":{"rendered":"http:\/\/www.neschle.de\/index.php\/blog\/leon-neschle-51-7-woche-2009\/"},"modified":"2020-06-20T16:02:40","modified_gmt":"2020-06-20T15:02:40","slug":"leon-neschle-51-7-woche-2009","status":"publish","type":"post","link":"https:\/\/neschle.de\/index.php\/blog\/leon-neschle-51-7-woche-2009\/","title":{"rendered":"Leon Neschle 51 (7. Woche 2009)"},"content":{"rendered":"<header>\n<h2 style=\"text-align: left;\"><strong><span style=\"color: #4f81bd\">Noch ein S\u00fcndenbock f\u00fcr die Finanzkrise: die universit\u00e4re Lehre!<\/span><\/strong><\/h2>\n<\/header>\n<p style=\"text-align: left;\"><em>Den gr\u00f6\u00dften Fehler, den wir jetzt machen k\u00f6nnten, w\u00e4re die Schuld beim Trainer zu suchen.&nbsp;<\/em>(Karl-Heinz K\u00f6rbel, Fu\u00dfballtrainer in der Bankenmetropole Frankfurt)<\/p>\n<p style=\"text-align: left;\">Ein wenig verschmitzt begr\u00fc\u00dften sie mich schon meine Studenten: zu einem Crash-Kurs \u00fcber Finanzmanagement. Wie es sich f\u00fcr einen Crash-Kurs geh\u00f6rt, gab es den Zusammensto\u00df gleich zu Anfang: \u201eM\u00fcssen Sie angesichts der Finanzkrise nicht ihre gesamte Lehre ver\u00e4ndern? M\u00fcssen die Lehrb\u00fccher nicht neu geschrieben werden?\u201c, war die diabolische Begr\u00fc\u00dfungsfrage. \u201eNein, ganz und gar nicht\u201c, lautete meine f\u00fcr die Studenten \u00fcberraschend provokative Antwort.<\/p>\n<p style=\"text-align: left;\">Alle dachten n\u00e4mlich, ich w\u00fcrde nun Asche \u00fcber mein Haupt streuen (m\u00fcssen). Doch ich machte das Gegenteil: Keine Selbstkritik des Wissenschaftlers, keine Verantwortungs\u00fcbernahme f\u00fcr die Finanzkrise? Nicht Schimpf und Schande auf das, was wir den Studenten seit Jahren beibringen. Nein!<\/p>\n<p style=\"text-align: left;\"><!--more--><\/p>\n<p style=\"text-align: left;\">Keiner will es gewesen sein?! Auch die Wissenschaft nicht. Das erinnert fatal an die b\u00f6sen Banker (Von den \u201eBad Banks\u201c, den \u201eb\u00f6sen Banken\u201c?) an der amerikanischen Mauerstra\u00dfe. Die genehmigten sich noch Ende Januar 2009 fette Pr\u00e4mien aus den steuerfinanzierten Subventionen ihrer maroden Geldbunker. Immer nach dem Motto: \u201eDer brave Mensch denkt an sich, selbst zuletzt!\u201c Man muss eben zur falschen Zeit an der richtigen Stelle ein wichtiges Zeichen (<b>,<\/b>) setzen. Keine Schuld den Bankern!<\/p>\n<p style=\"text-align: left;\">Ja, sind denn die Banker Schuld an der Finanzkrise oder die gierigen kleinen H\u00e4uslebauer, die nicht genug kriegen konnten von den billigen Krediten? Bis sie daran erstickt sind und die westliche Finanzwelt dazu? Und der heilige St. Blasius, der sonst immer gut gegen das Verschlucken ist? Der hat einfach zugesehen!<\/p>\n<h3 style=\"text-align: left;\"><strong>A. Die Selbstkritik hat viel f\u00fcr sich!? Jetzt sind die Profs dran!<\/strong><\/h3>\n<p style=\"text-align: left;\">Verantwortungsdiffusion allenthalben! Jeder w\u00e4lzt die Schuld f\u00fcr die Finanzkrise ab. Dabei m\u00fcssen wir uns doch nur ein Vorbild nehmen: am Fu\u00dfball. Dort sind immer die Trainer schuld, wenn etwas schiefgeht. Nie die Spieler oder der Vorstand. Doch die finanzwirtschaftlichen Trainer sind bei der Finanzkrise noch gar nicht richtig im Fokus. Die Trainer, das sind bei der Finanzkrise doch wohl die Professoren, die \u201eFinanzwirtschaft und Banken\u201c lehren. Schuld ist die Ausbildung! Schuld sind die Ausbilder! So (einfach) ist das!<\/p>\n<p style=\"text-align: left;\">Also Herr Professor, warum machen sie es sich dann nicht einfach? \u00dcben Sie Selbstkritik! Denn das wusste schon Wilhelm Busch:<\/p>\n<p style=\"text-align: center;\">\u201eDie Selbstkritik hat viel f\u00fcr sich.<\/p>\n<p style=\"text-align: center;\">Gesetzt den Fall, ich tadle mich;<\/p>\n<p style=\"text-align: center;\">So hab\u2019 ich erstens den Gewinn,<\/p>\n<p style=\"text-align: center;\">dass ich so h\u00fcbsch bescheiden bin;<\/p>\n<p style=\"text-align: center;\">Zum zweiten denken sich die Leut,<\/p>\n<p style=\"text-align: center;\">Der Mann ist lauter Redlichkeit;<\/p>\n<p style=\"text-align: center;\">Auch schnapp\u2019 ich drittens diesen Bissen<\/p>\n<p style=\"text-align: center;\">Vorweg den andern Kritik\u00fcssen;<\/p>\n<p style=\"text-align: center;\">Und viertens hoff\u2019 ich au\u00dferdem<\/p>\n<p style=\"text-align: center;\">Auf Widerspruch der mir genehm.<\/p>\n<p style=\"text-align: center;\">So kommt es denn zuletzt heraus,<\/p>\n<p style=\"text-align: center;\">Dass ich ein ganz famoses Haus.&#8220;<\/p>\n<p style=\"text-align: left;\">Doch es muss noch besser gehen: ohne Selbstkritik, aber mit demselben Ergebnis, wo am Ende herauskommt, dass wenigstens die Professoren der Finanzwirtschaft alles richtig gemacht haben. So, dass am Ende herauskommt, was der Trainer K\u00f6rbel von Zwietracht Frankfurt, direkt in der Bankenmetropole sagte: \u201eDen gr\u00f6\u00dften Fehler, den wir jetzt machen k\u00f6nnten, w\u00e4re die Schuld beim Trainer zu suchen.\u201c<\/p>\n<h3 style=\"text-align: left;\"><strong>B. Kommen Sie, Herr Professor, noch raus aus der Nummer?<\/strong><\/h3>\n<p style=\"text-align: left;\">Nein! Nat\u00fcrlich nicht! Aber wie soll ich rauskommen, wenn ich nie drin war. Au\u00dfer, mein lieber Herr Student, meine verehrte Dame Studentin, man hat mich einfach da reingedacht in diese Nummer. Denn:<\/p>\n<ol style=\"text-align: left;\">\n<li>Gesteigerte Gier ist eher dem Mangel des Besuchs von Religions- oder Ethikunterrichten zuzuschreiben als dem verst\u00e4rkten Besuch finanzwirtschaftlicher Vorlesungen. Denn wenn diese Gier den Geist verblendet, wird sogar den Blick auf \u201eGrundweisheiten des Finanzmanagements\u201c verstellt. Das aber wollen wir am wenigsten! Ist das dann also die Schuld der Finanzprofessoren?Statt die Ent-Ethisierung der Gesellschaft mitzumachen, nehmen Finanzprofessoren seit Jahren verst\u00e4rkt ethische Inhalte auf. Allenfalls kommen sie zu sp\u00e4t damit. Jeder Finanzmanager und jeder Banker muss zudem jenseits aller Finanzethik und Gier zwei Dinge ganz sicher wissen:\n<ol type=\"a\">\n<li>Niemand verschenkt etwas an den Finanzm\u00e4rkten: \u201eThere is no free lunch!\u201c Auff\u00e4llig hohe Anlagezinsen und niedrige Kreditzinsen, m\u00fcssen misstrauisch machen und nicht besoffen vor Freude \u00fcber den unerwarteten Fund! Letzteres konnte man aber nicht selten bei blau\u00e4ugigen Bankern beobachten und kann es noch.Dass einen Banker unerwartete \u201ewindfall profits\u201c treffen, ist umso unwahrscheinlicher, je vollkommener die M\u00e4rkte sind. Wo sich die Masse des Bankervolkes tummelt, gibt es aber keine gro\u00dfen Unvollkommenheiten des Marktes. \u00dcberraschungen gr\u00fcnden da eher auf Betrug.<\/li>\n<li>Auch beim Einstreichen einer hohen Rendite <i>nach<\/i> erfolgreicher Geldanlage muss man fragen, mit welchem Risiko sie zustande kam. Das Gemeine an der Ungewissheit ist n\u00e4mlich, dass sie zur Gewissheit wird und v\u00f6llig verschwindet, nachdem die Zukunft zur Gegenwart wurde. So kann man sich von hohen Gewinnen blenden lassen und das Gl\u00fcck beim n\u00e4chsten Mal herausfordern. Doch danach ist aus der Ungewissheit vielleicht die Gewissheit desastr\u00f6ser Verluste geworden.<\/li>\n<\/ol>\n<\/li>\n<li>Was die Leute falsch machen, die heute die Entscheidungen der Banken bestimmen, ist, soweit es \u00fcberhaupt mangelnder Ausbildung anzulasten ist, denen zuzuschreiben, die <i>gestern<\/i> deren Ausbildung gemacht haben. An den Hebeln der Macht sitzen heute diejenigen, die von meinen Vorg\u00e4ngern ausgebildet wurden. Meinen Vorg\u00e4ngern vorzuwerfen, sie h\u00e4tten ihren Studenten nichts von den gef\u00e4hrlichen strukturierten Produkten erz\u00e4hlt, ist m\u00fc\u00dfig, weil es diese Produkte damals zumindest in dieser Form noch gar nicht gab. Wer sie beschrieben h\u00e4tte, der h\u00e4tte als realit\u00e4tsferner Spinner gegolten.Es entscheiden also heute Leute, die von den Objekten ihrer Entscheidungen in ihrer Ausbildung noch nichts geh\u00f6rt haben k\u00f6nnen. Bei der Frage der Ausbildung kommt manchen Menschen offenbar die Zeitkomponente abhanden, wie auch in folgendem Beispiel.Neschle wurde einmal von seiner \u00f6rtlichen IHK als Dekan eines Fachbereichs um Unterst\u00fctzung gebeten. Die IHK wollte F\u00fchrungskr\u00e4fte im Umweltmanagement ausbilden. Dazu sollten die Professoren einen Beitrag leisten. In der Er\u00f6ffnungsveranstaltung sprach der IHK-Pr\u00e4sident die versammelten Unternehmer an und bedauerte, dass die IHK nun die Ausbildung im Umweltmanagement \u00fcbernehmen m\u00fcsse, <i>weil die Universit\u00e4t hier versage<\/i>. Meine Antwort darauf hat ihm damals nicht geschmeckt:\n<p>a. Wenn es wirklich so w\u00e4re, warum bem\u00fcht sich die IHK dann aktuell, Professoren als Lehrkr\u00e4fte f\u00fcr dieses Umwelt-Projekt zu gewinnen. b. Die aktuellen Stundenpl\u00e4ne der Universit\u00e4t sind derzeit prall gef\u00fcllt von umweltbezogenen Angeboten (Es \u00fcberrollte meine Uni gerade eine Umweltwelle!). Von Versagen k\u00f6nne aktuell also keine Rede sein. c. Das einzige Versagen k\u00f6nnte darin bestehen, dass die Unis sich nicht schon zu den Zeiten intensiver mit Umweltfragen besch\u00e4ftigt haben, in denen die jetzigen Umweltmanager ausgebildet wurden. Das war 10 \u2013 15 Jahre her, in den siebziger Jahren. Und da hat kaum jemand in dieser Richtung gedacht, erst recht und gerade nicht die Unternehmungen selbst.<\/p>\n<p>Der Vorwurf k\u00f6nnte gerechterweise nur lauten: Auch wenn niemand das gedacht und erwartet hat, von <i>Professoren <\/i>m\u00fcsste man es verlangen. \u2013 So falsch ist das nicht, wenn man selbst\u00e4ndige und mutige Hochschullehrer hat. H\u00e4tte die Uni damals aber so ausgebildet, h\u00e4tte man ihr vorgeworfen, mal wieder am Bedarf vorbei zu produzieren. Denn es ist gef\u00e4hrlich, dem Zeitgeist voraus zu sein. <i>Und es ist leichter, mit der Masse zu irren, als allein Recht zu haben! <\/i>Der brave Soldat Schwejk wurde einst sogar (zum wiederholten Male) f\u00fcr bl\u00f6d erkl\u00e4rt und eingelocht, weil er nach dem Mord in Sarajewo den Ersten Weltkrieg voraussagte.<\/li>\n<li>\u00dcber notwendige Weiterbildung l\u00e4sst sich jederzeit diskutieren. Doch dazu nimmt sich in der Regel die Praxis zu wenig Zeit. Je h\u00f6her der Manager in der Hierarchie, umso nachl\u00e4ssiger wird Weiterbildung betrieben. Dann entscheidet er jedoch \u00fcber etwas entschieden, \u00fcber das er nie intensiver nachgedacht hat. Und er sch\u00e4tzt die Tragweite seiner Entscheidungen falsch ein. Das gilt vor allem f\u00fcr das Massengift \u201eVerbriefung\u201c bzw. \u201estrukturierte Produkte\u201c. In meinen Vorlesungen kommen die schon seit Jahren vor, aber noch nicht in denen meiner Vorg\u00e4nger, bei denen die heutigen \u201eTop-Banker\u201c gelernt haben.Ich selbst habe in meiner Ausbildung auch nichts davon geh\u00f6rt! Doch ob es der Leser glauben mag oder nicht: Ich habe seit Jahren vor den Ausw\u00fcchsen dieser Instrumente gewarnt: Diejenigen, die vor geraumer Zeit dar\u00fcber entschieden haben, sa\u00dfen da l\u00e4ngst nicht mehr in Vorlesungen.<\/li>\n<\/ol>\n<p style=\"text-align: left;\">Also Selbstkritik? Warum? Da sehe ich keinen Anlass! \u00c4nderung der Vorlesungsinhalte? Auch nicht! \u2013 Doch halt! Nat\u00fcrlich! Endlich habe ich die Beispiele, die z.B. meine Warnungen vor der nicht beherrschbaren Komplexit\u00e4t der ABS- und CDOKonstruktionen st\u00fctzen. In dieser Hinsicht gibt es doch anschauliche \u00c4nderungen.<\/p>\n<h3 style=\"text-align: left;\"><strong>C. Bleibt alles anders, sagt Gr\u00f6nemeyer.<\/strong><\/h3>\n<p style=\"text-align: left;\">Ansonsten bleibt in den Vorlesungen alles anders. Anders als viele Leute sich das denken, die nach der Finanzkrise eine \u00c4nderung der Vorlesungsinhalte einfordern. F\u00fcr die Finanzkrise, die als \u201eSubprime-Krise\u201c begann und sich dann auswuchs, sind ja wohl vor allem folgende Ursachen verantwortlich:<\/p>\n<ol style=\"text-align: left;\">\n<li><i>Die Politik der US-Notenbank nach dem 11. September<\/i>: Sieht man darin die Hauptursache, dann ist das Trauma 911 viel gr\u00f6\u00dfer als bislang angenommen. Die scharfe Senkung der Zinsen danach sollte den Fall der amerikanischen Wirtschaft bremsen, der scharfe Anstieg wiederum die \u00dcberhitzung abk\u00fchlen. Statt aber die weitgehend ins Ausland verlegte Produktion anzuregen, sorgten die niedrigen Zinsen aber f\u00fcr vermehrten H\u00e4userbau und exzessive Entwicklungen bei den Immobilienpreisen. Der Anstieg der Zinsen trieb sp\u00e4ter dann viele Privatleute in die Insolvenz und das schneller als im \u201ealten Europa\u201c, weil im amerikanischen Hypothekenmarkt andere Kreditformen dominieren.<\/li>\n<li><i>Hypothekenvertr\u00e4ge in den USA<\/i>: Deutsche Hypothekenschuldner versichern sich regelm\u00e4\u00dfig gegen Zins\u00e4nderungen, indem sie die Zinsen f\u00fcr 5, 10 oder sogar f\u00fcr 15 Jahre festschreiben. F\u00fcr die Zinssicherheit nehmen sie einen etwas h\u00f6heren Zinssatz in Kauf. Unterstellen wir einmal eine durchschnittliche Laufzeit der Zinssicherung von knapp 7 Jahren, so stehen pro Jahr nur 15% der Vertr\u00e4ge f\u00fcr eine Neubewertung an. 85% sind von einer kurzfristigen Zins\u00e4nderung (vorerst) unber\u00fchrt, nach zwei Jahren immerhin noch 70% usw. Eine Zinssenkung oder Zinserh\u00f6hung l\u00e4uft sich also bei der Immobilienfinanzierung in Deutschland ganz langsam an den Wellenbrechern der langfristigen Zinsbindung tot.Amerikanische Hypotheken sind dagegen fast durchg\u00e4ngig mit variablen Zinss\u00e4tzen finanziert. Auf lange Sicht ist das zwar g\u00fcnstiger, weil die Versicherungspr\u00e4mie f\u00fcr die Zinsfestschreibung entf\u00e4llt. Doch kurzfristig trifft den Verbraucher das volle Zinsrisiko und die Zinspolitik der Notenbank schl\u00e4gt ungebremst und in vollem Umfang bis zum Verbraucher durch.<\/li>\n<li><i>Aggressives Marketing von Banken und Finanzvermittlern<\/i>: Die Zeiten sind l\u00e4ngst vorbei, in denen der Kreditsuchende dem\u00fctig einen Kredit-Antrag ausf\u00fcllte und sich dem Urteil des hoheitlichen Bank-Beamten \u00fcber seine Kredit-W\u00fcrdigkeit unterwarf, weil er seine Bankverbindung so selten wechselte wie seine Staatsb\u00fcrgerschaft. Doch ist das Gegenteil davon richtig? Aggressives Aufdr\u00e4ngen von Krediten. \u00dcberreden statt \u00fcberzeugen?Diese Form des Bankmarketings bestimmte jedoch das Hypothekengesch\u00e4ft w\u00e4hrend der Niedrigzinsphase nach 911. Und die Haftungsmasse Haus schien ja st\u00e4ndig im Wert zu steigen. Da konnte man doch auch schon mal ein wenig davon vorwegnehmen und den Kreditbetrag \u00fcber den Gegenwartswert erh\u00f6hen. Das Gift in dieser L\u00f6sung schmeckten die Schuldner erst nach der folgenden Zinserh\u00f6hung bei gleichzeitigem sinken der Hauspreise. Und dieses Gift wirkt durch Liquidit\u00e4tsentzug bis hin zum Austrocknen des wirtschaftlichen K\u00f6rpers.<\/li>\n<li><i>Risiko\u00fcbertragung durch strukturierte Bankprodukte<\/i>: Eine Bank ist eigentlich keine Versicherung. Dennoch schlie\u00dft sie bei jedem Kreditvertrag mit dem Kreditnehmer eine Versicherung \u00fcber die Restschuld ab, f\u00fcr die sie geradesteht, wenn der Kunde nicht zahlen kann. Die Versicherungsmasse daf\u00fcr ist das Eigenkapital der Bank, das alle nicht-fremdversicherten Risiken und alle nicht versicherbaren Risiken deckt.Gibt die Bank das Risiko der Restschuldversicherung weiter, wird die Belastung des Eigenkapitals geringer. Das geschah auf breiter Front. Die Risiken wurden neu verpackt und im B\u00fcndel weitergegeben. \u00dcber diese Verbriefungen konnten insbesondere Banken daran wieder Anteile erwerben. Die Konstruktionen waren so komplex, dass sie selbst von den Bankern kaum verstanden wurde. Verdient haben daran vor allem amerikanische Anw\u00e4lte, die von der Konstruktion von Komplexit\u00e4ten weltweit profitieren.<\/li>\n<li><i>Die Rating-Agenturen, ihre Methoden und Risikobewertungen<\/i>: Die Verzinsung der verbrieften Anteile h\u00e4ngt wiederum vom Risiko ab. Dieses Risiko beurteilen insbesondere die weltweit t\u00e4tigen amerikanischen Rating-Agenturen. Bei den amerikanischen Immobilienkrediten kamen die Verbriefungskonstruktionen vielfach auf die beste Risikobewertung AAA. \u2013Da dreht sich doch der Markowitz im Grabe um! Eine risikomindernde \u201eStreuung\u201c der Anlagen, die eigentlich kaum keine ist: in einer <i>einzigen<\/i> Branche (Immobilien, meist sogar allein Wohnimmobilien) und einem <i>einzigen<\/i> Land (USA). Oh, Gott welcher Leichtsinn! Allein die Konzentration auf ein einziges Land macht das Risiko aus, allein abh\u00e4ngig zu sein von der Zinspolitik einer einzigen Notenbank. Und gerade die fuhr einen Schlingerkurs (siehe 1.).<\/li>\n<li><i>Die zeitnahe Bewertung in den Bankbilanzen<\/i>: Die Anpassung der bundesdeutschen Bilanzierung an die zeitaktuelle Bewertung der internationalen Rechnungslegung verst\u00e4rkt die Rasanz der Krisen\u00fcbertragung \u00fcber die Bank-Bilanzen. Hier ist man zu Abwertungen auch gezwungen, wenn Wertminderungen voraussichtlich nicht von Dauer sind.<\/li>\n<\/ol>\n<p style=\"text-align: left;\">\u00dcberraschend ist allenfalls die Ballung dieser Risiken. F\u00fcr sich genommen sind sie nichts Besonderes und daher schon Gegenstand des akademischen Unterrichts. Allein: Vor allem die Verbriefungstechnik hat sich in dieser Form erst in der j\u00fcngsten Vergangenheit entwickelt. Wahrscheinlich brauchten die amerikanischen Anw\u00e4lte eine neue Verdienstquelle!<\/p>\n<p style=\"text-align: left;\">Muss ich mich also f\u00fcr die Finanzkrise entschuldigen? Entschuldigung, aber ich bin entschuldigt! Wir sollten die Schuld nicht beim Trainer suchen, wie Herr K\u00f6rbel richtig bemerkt. Doch auch Trainer k\u00f6nnen irren. Wie sagte n\u00e4mlich einst Willi Entenmann, Trainer beim VfB Stuttgart: \u201eDas Schiff hat Schlagseite. Es l\u00e4sst sich nur wieder aufrichten, wenn wir alle auf dieselbe Seite gehen.\u201c<\/p>\n<p style=\"text-align: left;\">Vielleicht sollten wir dabei ein wenig vorsichtiger sein. Denn so hat das die US-Notenbank nach 911 auch versucht, radikale Zinssenkung und dann radikale Erh\u00f6hung. Wenn das die Bew\u00e4ltigung der Finanzkrise ausmachen soll, dann kommen wir bald in eine noch gr\u00f6\u00dfere. Aber da soll mir dann keiner sagen, ich h\u00e4tte dazu nichts gesagt. Ihr habt nur nicht geh\u00f6rt! Doch was soll der Trainer denn machen, wenn die Spieler auf dem Feld sind und ihn nicht h\u00f6ren.<\/p>\n<p style=\"text-align: left;\">\n<p style=\"text-align: center;\">Beim Fu\u00dfball da ist schuld der Trainer<\/p>\n<p style=\"text-align: center;\">Und von den Spielern ist es keener.<\/p>\n<p style=\"text-align: center;\">Und bei der internationalen Krise<\/p>\n<p style=\"text-align: center;\">War keiner von den Bankern miese.<\/p>\n<p style=\"text-align: center;\">Verursacht hat den ganzen Mist,<\/p>\n<p style=\"text-align: center;\">der Kerl der heut\u2019 Professor ist.<\/p>\n<p style=\"text-align: center;\">Oder vielleicht nicht?<\/p>\n<p><a title=\"PDF-Datei\" href=\"http:\/\/www.neschle.de\/download-manager.php?id=128\">PDF-Datei<\/a><br \/>\nThis post was downloaded by  1201  people until now.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noch ein S\u00fcndenbock f\u00fcr die Finanzkrise: die universit\u00e4re Lehre! Den gr\u00f6\u00dften Fehler, den wir jetzt machen k\u00f6nnten, w\u00e4re die Schuld beim Trainer zu suchen.&nbsp;(Karl-Heinz K\u00f6rbel, Fu\u00dfballtrainer in der Bankenmetropole Frankfurt) Ein wenig verschmitzt begr\u00fc\u00dften sie mich schon meine Studenten: zu einem Crash-Kurs \u00fcber Finanzmanagement. Wie es sich f\u00fcr einen Crash-Kurs geh\u00f6rt, gab es den Zusammensto\u00df &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/neschle.de\/index.php\/blog\/leon-neschle-51-7-woche-2009\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eLeon Neschle 51 (7. Woche 2009)\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,6],"tags":[59,10,18,12],"_links":{"self":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/382"}],"collection":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/comments?post=382"}],"version-history":[{"count":2,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/382\/revisions"}],"predecessor-version":[{"id":1011,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/382\/revisions\/1011"}],"wp:attachment":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/media?parent=382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/categories?post=382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/tags?post=382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}