{"id":371,"date":"2008-10-30T10:22:07","date_gmt":"2008-10-30T09:22:07","guid":{"rendered":"http:\/\/www.neschle.de\/index.php\/ulkereien\/ulkerei-26\/"},"modified":"2020-06-19T20:39:56","modified_gmt":"2020-06-19T19:39:56","slug":"ulkerei-26","status":"publish","type":"post","link":"https:\/\/neschle.de\/index.php\/ulkereien\/ulkerei-26\/","title":{"rendered":"Ulkerei 26"},"content":{"rendered":"<header>\n<h2><strong><span style=\"color: #4f81bd\">Chuck und sein Gaul oder Wie das amerikanische Finanz-System funktioniert<\/span><\/strong><\/h2>\n<\/header>\n<p style=\"text-align: left;\">Hier die Erfolgsgeschichte aus dem Amiland.<\/p>\n<p style=\"text-align: left;\">Der junge Chuck will mit einer eigenen Ranch reich werden. Als Anfang kauft er einem Farmer ein Pferd ab.<\/p>\n<p style=\"text-align: left;\">Er \u00fcbergibt dem Farmer seine ganzen 100 Dollar und dieser verspricht, ihm das Pferd am n\u00e4chsten Tag zu liefern.<\/p>\n<p style=\"text-align: left;\">Am n\u00e4chsten Tag kommt der Farmer vorbei und teilt Chuck eine schlechte Nachricht mit: &#8222;Es tut mir leid, Kleiner, aber das Tier ist in der Nacht tot umgefallen.&#8220; Meint Chuck: &#8222;Kein Problem, gib mir einfach mein Geld zur\u00fcck.\u201c<!--more--><\/p>\n<p style=\"text-align: left;\">&#8222;Geht nicht&#8220;, erwidert ihm der Farmer. &#8222;Ich habe das Geld gestern bereits f\u00fcr D\u00fcnger ausgegeben.&#8220;<\/p>\n<p style=\"text-align: left;\">Chuck \u00fcberlegt kurz. &#8222;Na dann&#8220;, f\u00e4ngt er an, &#8222;nehme ich das tote Biest trotzdem.&#8220; &#8222;Wozu denn?&#8220; fragt der Farmer., &#8222;Ich will es verlosen&#8220;, erkl\u00e4rt ihm Chuck. &#8222;Du kannst doch kein totes Pferd verlosen!&#8220;, staunt der Farmer.<\/p>\n<p style=\"text-align: left;\">Doch Chuck antwortet: &#8222;Kein Problem! Ich erz\u00e4hl&#8216; einfach keinem, dass es schon tot ist&#8230;&#8220;<\/p>\n<p style=\"text-align: left;\">Monate sp\u00e4ter laufen sich Chuck &#8211; fein in Anzug und schicken Schuhen &#8211; und der Farmer in der Stadt \u00fcber den Weg.<\/p>\n<p style=\"text-align: left;\">Der Farmer fragt: &#8222;Chuck! Wie lief&#8217;s denn mit der Verlosung des Pferde-Kadavers?&#8220; &#8211; &#8222;Spitze&#8220;, erz\u00e4hlt ihm Chuck.<\/p>\n<p style=\"text-align: left;\">&#8222;Ich habe \u00fcber 500 Lose zu je 2 Dollar verkauft und meine ersten 1.000 Dollar Profit gemacht.&#8220; &#8211; &#8222;Ja&#8230; gab&#8217;s denn keine Reklamationen?&#8220; &#8211; &#8222;Doch &#8211; vom Gewinner&#8220;, sagt Chuck. &#8222;Dem habe ich dann einfach seine 2 Dollar zur\u00fcckgegeben.&#8220;<\/p>\n<p style=\"text-align: left;\">Heute verkauft Chuck strukturierte Finanzprodukte bei Goldman Sachs.<\/p>\n<p style=\"text-align: left;\">\u2026und jetzt haben wir den Salat!<\/p>\n<p><a title=\"PDF-Datei\" href=\"http:\/\/www.neschle.de\/download-manager.php?id=124\">PDF-Datei<\/a><br \/>\nThis post was downloaded by  1980  people until now.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chuck und sein Gaul oder Wie das amerikanische Finanz-System funktioniert Hier die Erfolgsgeschichte aus dem Amiland. Der junge Chuck will mit einer eigenen Ranch reich werden. Als Anfang kauft er einem Farmer ein Pferd ab. Er \u00fcbergibt dem Farmer seine ganzen 100 Dollar und dieser verspricht, ihm das Pferd am n\u00e4chsten Tag zu liefern. Am &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/neschle.de\/index.php\/ulkereien\/ulkerei-26\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eUlkerei 26\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[59],"_links":{"self":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/371"}],"collection":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/comments?post=371"}],"version-history":[{"count":1,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/371\/revisions"}],"predecessor-version":[{"id":914,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/371\/revisions\/914"}],"wp:attachment":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/media?parent=371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/categories?post=371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/tags?post=371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}