{"id":1249,"date":"2020-12-23T10:01:00","date_gmt":"2020-12-23T09:01:00","guid":{"rendered":"https:\/\/neschle.de\/?p=1249"},"modified":"2020-12-28T12:23:09","modified_gmt":"2020-12-28T11:23:09","slug":"leon-neschle-85-93","status":"publish","type":"post","link":"https:\/\/neschle.de\/index.php\/blog\/leon-neschle-85-93\/","title":{"rendered":"Leon Neschle 85-93: Vorbemerkung"},"content":{"rendered":"\n<h2 class=\"has-text-color\" style=\"color:#4f81bd\"><strong>Die Erbs\u00fcnden des Liberalismus &#8211; Essay in neun Teilen und sieben S\u00fcnden<\/strong><\/h2>\n\n\n\n<p><em>\u201eFreiheit ist ein Geschenk, das sich nicht jeder gern machen l\u00e4sst<\/em>&#8220; (Thomas Willmann \u201eDas finstere Tal\u201c)<\/p>\n\n\n\n<h3><strong>Vorbemerkung und Vorschau zum gesamten Essay (85-93)<\/strong><\/h3>\n\n\n\n<p>Hat sich der Liberalismus mit dem Niedergang des Sozialismus in Osteuropa totgesiegt? Gibt es nicht weltweit m\u00e4chtigen Aufwind f\u00fcr antiliberale Kr\u00e4fte und den \u201eR\u00fcckbau von Rechtstaatlichkeit, Meinungs- und Pressfreiheit\u201c<a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftn1\"><sup>[1]<\/sup><\/a>? Sind \u201eAutokratien auf dem Vormarsch\u201c<a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftn2\"><sup>[2]<\/sup><\/a>: in Ungarn, Indien, Brasilien, Russland, China, in den USA des Donald Trump? K\u00f6nnen wir sogar das Todesdatum des Liberalismus vorhersagen?&nbsp;<\/p>\n\n\n\n<p>Der Bestsellerautor Harari behauptet ja: Das ist der Tag, an dem \u201emich das System besser kennt als ich mich selbst\u201c.<a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftn3\"><sup>[3]<\/sup><\/a>&nbsp;Mit \u201eSystem\u201c meint er die Datenbanken von Google und Co. Dieser Tag des Untergangs sei nahe. Sehr gewiss und sehr nahe!&nbsp;<\/p>\n\n\n\n<p>L\u00e4ge Harari richtig, w\u00e4re es unsinnig, diesen Artikel \u00fcber Liberalismus noch zu schreiben oder ihn zu lesen. Doch Harari liegt falsch! Das aber werde ich an anderer Stelle belegen.&nbsp;<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Hier geht es um etwas anderes, \u00fcber das Friedrich August von Hayek vor \u00fcber 70 Jahren in einem auf Englisch erschienenen Artikel geunkt hat: \u201eNachdem die wesentlichen Forderungen des liberalen Programms erf\u00fcllt waren, vernachl\u00e4ssigten die liberalen Denker die Fortbildung der philosophischen Grundlagen; der Liberalismus h\u00f6rte damit auf, ein lebendiges Problem zu sein, das zu geistiger Arbeit reizte\u201c.<a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftn4\"><sup>[4]<\/sup><\/a>&nbsp;Das k\u00f6nnte eine der Ursachen daf\u00fcr sein, dass die FDP heute nicht nur f\u00fcr Christoph Seils<a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftn5\"><sup>[5]<\/sup><\/a>&nbsp;\u201eintellektuell blank\u201c daherkommt und zu einem Personenwahlverein ohne liberale Programmatik zu verkommen scheint, wie allerdings andere Parteien auch.<\/p>\n\n\n\n<p>Nach langer philosophischer Apathie k\u00e4mpft der Liberalismus heute noch mit Vorderlader und Haubitze seiner Gr\u00fcnderzeit, w\u00e4hrend seine populistischen und totalit\u00e4ren Gegner die Menschen mit den Cyber-Kontrollwaffen des Internets bei jedem Click \u201efreiwillig\u201c in die Unfreiheit entf\u00fchren. F\u00fcr Harari bedeuten diese Waffen den Untergang des Liberalismus. Doch er sagt nicht, was den Liberalismus ersetzen wird<a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftn6\"><sup>[6]<\/sup><\/a>&nbsp;und ob das von ihm vorhergesagte Ende des Liberalismus eine bessere Zukunft f\u00fcr die Menschheit verspricht. Auch weil er selbst Zweifel daran hat, scheint es der M\u00fche wert, das angeblich \u201eunab\u00e4nderliche\u201c Schicksal des Liberalismus abzuwenden:<\/p>\n\n\n\n<p>Lange Zeit schon ruft das liberale Denken nach Erneuerung, auch wenn einflussreiche Liberale meinen \u201eDer Liberalismus lebt. Er braucht keine Erneuerung\u201c.<a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftn7\"><sup>[7]<\/sup><\/a>&nbsp;Was f\u00fcr ein Irrtum! Sp\u00e4testens seit Darwin wissen wir: Alles was lebt, muss sich permanent wandeln und erneuern, schon weil sich rundherum alles ver\u00e4ndert. Der Liberalismus der Informations- und Wissensgesellschaft kann nicht derselbe sein wie der in vorindustrieller Zeit. Die Urv\u00e4ter des Liberalismus haben bei weitem nicht alles vorhergesehen. Sie waren brillante Denker, aber keine Propheten.<\/p>\n\n\n\n<p>Was sich nicht erneuert, ist tot, zumindest aber lethargisch. Daher k\u00fcndet das obige Zitat Hayeks von liberaler Lethargie. Will man daraus Erwachen, schreit das nach Aufbruch. Der aber kann nur gelingen, wenn der Ausgangspunkt und das Ziel liberalen Denkens klar sind. Dazu muss man \u201ezuerst vor der eigenen Haust\u00fcr kehren\u201c, ganz im Sinne des \u201eColloque Walter Lippmann\u201c, das 1938 in Paris bereits einmal diese Erneuerung ins Leben gerufen hat und das als&nbsp;<em>Nukleus des Neoliberalismus<\/em>&nbsp;und seiner sp\u00e4teren Spielarten gilt.<a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftn8\"><sup>[8]<\/sup><\/a><\/p>\n\n\n\n<p>Verfolgt man die oft \u201eselbstqu\u00e4lerischen Debatten\u201c der \u201eNeoliberalen\u201c dort, findet man nichts von dem, was dem \u201eNeo-Liberalismus\u201c heute allem von linken, rechten und religi\u00f6sen Fundamentalisten vorgeworfen wird: nichts von einer \u201earroganten Philosophie\u201c, nichts von \u201eder \u00d6konomisierung aller Lebensbereiche\u201c, nichts von der Forderung nach einem \u201eungez\u00fcgelten Markt\u201c. Das \u201eneo-liberale\u201c Feindbild der Linken entsteht erst Ende der 70er Jahre, nachdem die Politik von Margaret Thatcher und Ronald Reagan auf umfassende Privatisierung, Vermarktlichung und die Deregulierung der Finanzm\u00e4rkte setzte<a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftn9\"><sup>[9]<\/sup><\/a>. Dieser \u201eNeo-Liberalismus\u201c ist jedoch tats\u00e4chlich ein \u201eNeo-Neo-Liberalismus\u201c.<a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftn10\"><sup>[10]<\/sup><\/a>&nbsp;Ist eindeutig dieser Typus gemeint, wird er zur Unterscheidung mit Bindestrich als \u201eNeo-Liberalismus\u201c geschrieben, auch in Zitaten.<\/p>\n\n\n\n<p>Heute schreiben die Linken ihren Kampfbegriff dennoch \u201eNeoliberalismus\u201c, weil sie den urspr\u00fcnglichen Neoliberalismus bis auf wenige Ausnahmen (z.B. Sahra Wagenknecht) ignorieren. Ihr Neo-Liberalismus der&nbsp;<em>alten wei\u00dfen M\u00e4nner<\/em>&nbsp;ist vor allem in der feministischen Version an die Stelle des Kapitalismus getreten, auch weil Kapitalisten das Wort \u201eKapitalismus\u201c seit dem Niedergang des Sozialismus mit Stolz verwenden. Der Kapitalismus hat gesiegt und jahrzehntelange Prophezeiungen der Linken \u00fcber seinen Untergang sind gescheitert, aus Sicht der Linken allerdings nur vorerst. Die Linke braucht daher einen neuen Feind, den sie glaubt besiegen zu k\u00f6nnen, ideologisch und real: den \u201eNeo-Liberalismus\u201c. Dieser (Neo-)Neo-Liberalismus hat wie der urspr\u00fcngliche Neoliberalismus seine Wurzeln im Klassischen Liberalismus. Damit tr\u00e4gt auch er die Last der Geschichte aller liberalen Bewegungen.&nbsp;<\/p>\n\n\n\n<p>Um diese Geschichte geht es hier. Dennoch bezieht sich der Beitrag meist auf zeitgen\u00f6ssische Quellen. Im Stil lehnt er sich an wissenschaftliches Vorgehen an, ohne dessen ganzer Strenge zu gen\u00fcgen. Relevanz geht hier vor Eleganz. Geboten wird eine geerdete politische Philosophie mit Bildern zum Anfassen.&nbsp;<\/p>\n\n\n\n<p>Wer sich fragt, warum die Auseinandersetzung in diesem Essay vor allem mit der Linken stattfindet: Das liegt&nbsp;<em>allein<\/em>&nbsp;daran, dass die anti-akademische Rechte intellektuell zu wenig zu bieten hat und die religi\u00f6sen Fundamentalisten geistig isoliert und esoterisch daherkommen. Da hat die geistige Auseinandersetzung weder Angriffspunkt noch Reiz. Die rechten Anti-Liberalen sind mangels ideologischer Masse sogar fast indiskutabel. Daher bleiben eben&nbsp;<em>fast<\/em>&nbsp;nur noch die Linken.<\/p>\n\n\n\n<p>Und auch da ist die Auseinandersetzung nicht leicht. Denn \u201eLinke bleiben gerne unter sich. Man trifft sich auf den immer gleichen Podien, man verleiht sich gegenseitig Preise f\u00fcr den Mut, Dinge auszusprechen, mit denen alle einverstanden sind. Das verhindert aber eine offene Debattenkultur.\u201c<a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftn11\"><sup>[11]<\/sup><\/a><\/p>\n\n\n\n<p>Da bleibt nichts anderes, als eine solche Debatte zu er\u00f6ffnen: in der Hoffnung, dass andere darauf reagieren und auch Gegner des Liberalismus den Versuch machen, sich offen mit den Argumenten auseinanderzusetzen, auch wenn ihnen das au\u00dferhalb ihrer dogmatischen Scheuklappen und Vorurteile schwerzufallen scheint.<\/p>\n\n\n\n<p>Das Folgende bietet eine kritische Selbstbespiegelung des Liberalismus, die auch vielen Liberalen nicht immer schmecken wird. Die neun Teile, beginnen mit einem Grundlagenteil (Neschle 85). Es folgen sieben \u201eErbs\u00fcnden\u201c (Neschle 86-92), die von Gegnern des Liberalismus zum Teil als \u201eTods\u00fcnden\u201c verstanden werden Nicht alle dieser S\u00fcnden sind dem Liberalismus in die Wiege gelegt. Einige werden ihm von seinen Gegnern und von Liberalen selbst nur zugeschrieben, insbesondere durch Verwechslung von Liberalen mit Libert\u00e4ren, die Missachtung der urspr\u00fcnglichen Neoliberalen um die Freiburger Schule und die \u00dcberrepr\u00e4sentanz der (Neo-)Neo-Liberalen der Chicago School bei Gegnern der Liberalen, die ein besseres Ziel f\u00fcr sie bieten. Dieses Essay endet mit einem zusammenfassenden \u00dcberblick (Neschle 93) und einem Ausblick in die weitere Entwicklung des Liberalismus.<\/p>\n\n\n\n<p>Dass dieser Beitrag entstanden ist, habe ich vor allem zwei Menschen zu verdanken: Xorto Erdogan, der mich fast gezwungen hat, meine Gedanken zum Liberalismus aufzuschreiben, und Dr. Arthur Dill, der nicht nur meine technischen Defizite ausgeglichen hat. Ohne seinen Zuspruch und den seiner Familie w\u00e4re der Neschle in der Versenkung verschwunden. Danke von Herzen!<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftnref1\"><sup>[1]<\/sup><\/a>&nbsp;Christoph David Piorkowski, Forschung \u00fcber Ursachen der Krise \u2013 Liberale Demokratien in Bedr\u00e4ngnis,&nbsp;<a href=\"https:\/\/www.tagesspiegel.de\/wissen\/forschung-ueber-ursachen-der-krise-liberale-demokratien-in-bedraengnis\/24521584.html\">https:\/\/www.tagesspiegel.de\/wissen\/forschung-ueber-ursachen-der-krise-liberale-demokratien-in-bedraengnis\/24521584.html<\/a>. (21.03.20) Vgl. dort auch das Folgende.<\/p>\n\n\n\n<p><a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftnref2\"><sup>[2]<\/sup><\/a>&nbsp;Vgl. dazu den Bericht der Tagesschau \u201eTransformationsindex \u2013 Autokratien auf dem Vormarsch\u201c \u00fcber eine Bertelmann-Studie,&nbsp;&nbsp;<a href=\"https:\/\/www.tagesschau.de\/inland\/bertelsmann-studie-autokratien-101.html\">https:\/\/www.tagesschau.de\/inland\/bertelsmann-studie-autokratien-101.html<\/a>. (29.04.2020)<\/p>\n\n\n\n<p><a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftnref3\"><sup>[3]<\/sup><\/a>&nbsp;Yuval Noah Harari, Homo Deus \u2013 Eine Geschichte von Morgen, 9. Auflage M\u00fcnchen 2019, S.512. Die Behauptung ist schon \u00fcberraschend in einem Buch, dessen Autor an anderer Stelle (S. 78) schreibt: \u201eViele Wissenschaftler versuchen vorherzusagen, wie die Welt im Jahr 2100 oder2200 aussehen wird. Das ist reine Zeitverschwendung.\u201c<\/p>\n\n\n\n<p><a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftnref4\"><sup>[4]<\/sup><\/a>&nbsp;Zitiert nach Clemens Schneider, Ein neuer Ungeist lockt Menschen in die Selbstentm\u00fcndigung,&nbsp;<a href=\"https:\/\/www.welt.de\/debatte\/kommentare\/article192141493\/Clemens-Schneider-Liberale-muessen-einen-neuen-Ungeist-bekaempfen.html\">https:\/\/www.welt.de\/debatte\/kommentare\/article192141493\/Clemens-Schneider-Liberale-muessen-einen-neuen-Ungeist-bekaempfen.html<\/a>. (09.01.20) Eine leicht abweichende \u00dcbersetzung bei Friedrich August von Hayek, Die Intellektuellen und der Sozialismus (Teil 2),&nbsp;<a href=\"https:\/\/www.misesde.org\/2015\/09\/die-intellektuellen-und-der-sozialismus-teil-2\/\">https:\/\/www.misesde.org\/2015\/09\/die-intellektuellen-und-der-sozialismus-teil-2\/<\/a>. (12.01.20)<\/p>\n\n\n\n<p><a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftnref5\"><sup>[5]<\/sup><\/a>&nbsp;Vgl. Christoph Seils, FDP \u2013 Intellektuell blank,&nbsp;<a href=\"https:\/\/www.zeit.de\/politik\/deutschland\/2020-06\/fdp-krise-liberalismus-hannah-arendt\">https:\/\/www.zeit.de\/politik\/deutschland\/2020-06\/fdp-krise-liberalismus-hannah-arendt<\/a>.<\/p>\n\n\n\n<p><a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftnref6\"><sup>[6]<\/sup><\/a>&nbsp;Damit haben auch andere M\u00fche, etwa Robert Nef, Der Liberalismus ist tot \u2013 aber was ist die Alternative,&nbsp;<a href=\"https:\/\/www.luzernerzeitung.ch\/meinung\/was-wird-als-alternative-zur-offenen-gesellschaft-mit-privateigentum-wirtschaftsfreiheit-und-marktwirtschaft-angeboten-ld.1166595\">https:\/\/www.luzernerzeitung.ch\/meinung\/was-wird-als-alternative-zur-offenen-gesellschaft-mit-privateigentum-wirtschaftsfreiheit-und-marktwirtschaft-angeboten-ld.1166595<\/a>. (28.04.2020)<\/p>\n\n\n\n<p><a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftnref7\"><sup>[7]<\/sup><\/a>&nbsp;Karl-Heinz Paqu\u00e9, Der Liberalismus lebt. Er braucht keine Erneuerung,&nbsp;<a href=\"https:\/\/www.welt.de\/debatte\/kommentare\/plus183442612\/Die-Kraft-der-FDP-Der-Liberalismus-lebt-Er-braucht-keine-Erneuerung.html\">https:\/\/www.welt.de\/debatte\/kommentare\/plus183442612\/Die-Kraft-der-FDP-Der-Liberalismus-lebt-Er-braucht-keine-Erneuerung.html<\/a>. (20.04.2020)<\/p>\n\n\n\n<p><a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftnref8\"><sup>[8]<\/sup><\/a>&nbsp;Vgl. dazu Karen Horn, Geboren aus der Krise, Der Neoliberalismus wird achtzig,&nbsp;<a href=\"https:\/\/www.faz.net\/aktuell\/finanzen\/finanzmarkt\/neoliberalismus-wird-achtzig-geboren-aus-dem-geist-der-krise-15733799.html\">https:\/\/www.faz.net\/aktuell\/finanzen\/finanzmarkt\/neoliberalismus-wird-achtzig-geboren-aus-dem-geist-der-krise-15733799.html<\/a>. Dort auch das Folgende dieses Absatzes. (21.01.20)<\/p>\n\n\n\n<p><a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftnref9\"><sup>[9]<\/sup><\/a>&nbsp;Vgl. dazu Andreas Reckwitz, Neoliberalismus \u2013 Der Markt unserer W\u00fcnsche,&nbsp;<a href=\"https:\/\/www.zeit.de\/2018\/49\/neoliberalismus-postindustrielle-gesellschaft-polarisierung-beschaeftigungsstruktur-vermarktung-alltagskultur\">https:\/\/www.zeit.de\/2018\/49\/neoliberalismus-postindustrielle-gesellschaft-polarisierung-beschaeftigungsstruktur-vermarktung-alltagskultur<\/a>. (24.01.20)<\/p>\n\n\n\n<p><a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftnref10\"><sup>[10]<\/sup><\/a>&nbsp;So auch Dieter Schnaas, Liberalismus \u2013 Der Sinn der Freiheit,&nbsp;<a href=\"https:\/\/www.google.com\/search?client=firefox-b-d&amp;q=Dieter+Schnaas%2C+Liberalismus+%E2%80%93+Der+Sinn+der+Freiheit\">https:\/\/www.google.com\/search?client=firefox-b-d&amp;q=Dieter+Schnaas%2C+Liberalismus+%E2%80%93+Der+Sinn+der+Freiheit<\/a>. (23.03.20)<\/p>\n\n\n\n<p><a href=\"applewebdata:\/\/DF1E5F66-181A-452B-848F-064850D3A2A3#_ftnref11\"><sup>[11]<\/sup><\/a>&nbsp;Ninve Ermagan, G\u00fcner Balci \u2013 Diese Frau wei\u00df genau, wie es Migranten in Berlin-Neuk\u00f6lln geht.&nbsp;<a href=\"https:\/\/www.welt.de\/debatte\/kommentare\/plus213737354\/Guener-Balci-Diese-Frau-weiss-genau-wie-es-Migranten-in-Berlin-Neukoelln-geht.html?notify=success_subscription\">https:\/\/www.welt.de\/debatte\/kommentare\/plus213737354\/Guener-Balci-Diese-Frau-weiss-genau-wie-es-Migranten-in-Berlin-Neukoelln-geht.html?notify=success_subscription<\/a>. (18.08.2020)<\/p>\n\n\n<p style=\"text-align: left;\"><span style=\"font-size: =;\"><a href=\"http:\/\/www.neschle.de\/download-manager.php?id=221\">PDF-Datei<\/a><span style=\"font-size: small;\"><br>This post was downloaded by  418 people until now.<\/span><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Die Erbs\u00fcnden des Liberalismus &#8211; Essay in neun Teilen und sieben S\u00fcnden \u201eFreiheit ist ein Geschenk, das sich nicht jeder gern machen l\u00e4sst&#8220; (Thomas Willmann \u201eDas finstere Tal\u201c) Vorbemerkung und Vorschau zum gesamten Essay (85-93) Hat sich der Liberalismus mit dem Niedergang des Sozialismus in Osteuropa totgesiegt? Gibt es nicht weltweit m\u00e4chtigen Aufwind f\u00fcr antiliberale &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/neschle.de\/index.php\/blog\/leon-neschle-85-93\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eLeon Neschle 85-93: Vorbemerkung\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,6],"tags":[111,14,110,109],"_links":{"self":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/1249"}],"collection":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/comments?post=1249"}],"version-history":[{"count":11,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/1249\/revisions"}],"predecessor-version":[{"id":1520,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/1249\/revisions\/1520"}],"wp:attachment":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/media?parent=1249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/categories?post=1249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/tags?post=1249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}