{"id":1232,"date":"2020-08-14T16:47:06","date_gmt":"2020-08-14T15:47:06","guid":{"rendered":"https:\/\/neschle.de\/?p=1232"},"modified":"2020-08-15T10:28:03","modified_gmt":"2020-08-15T09:28:03","slug":"leon-neschle-84","status":"publish","type":"post","link":"https:\/\/neschle.de\/index.php\/blog\/leon-neschle-84\/","title":{"rendered":"Leon Neschle 84"},"content":{"rendered":"\n<h2><strong><span style=\"color:#4f81bd\" class=\"tadv-color\">Meine Freiheit, Deine Freiheit \u2013 Die Freiheit, \u201eFreiheit\u201c (nicht) zu verstehen<\/span><\/strong><\/h2>\n\n\n\n<p><em>Freiheit, die ich meine <\/em>(Max von Schenkendorf, oft benutzt, oft missbraucht)<\/p>\n\n\n\n<h3 class=\"has-text-align-left\"><strong>Vorbemerkung<\/strong><\/h3>\n\n\n\n<p>Liberal sein, hei\u00dft f\u00fcr Freiheit sein.&nbsp;Aber f\u00fcr welche Freiheit? F\u00fcr meine Freiheit, f\u00fcr Deine Freiheit? F\u00fcr die Freiheit aller anderen? \u00dcber alle Grenzen hinaus? Was ist mit der Freiheit meiner Enkel und Urenkel? Wie steht es mit der Freiheit von Organisationen und Kollektiven? Wie mit der Freiheit von Systemen? Gibt es die \u00fcberhaupt?<\/p>\n\n\n\n<p>Und f\u00fcr welche Art von Freiheit?&nbsp;F\u00fcr passive (negative) Freiheit VON etwas? Aber wovon? Oder f\u00fcr aktive (positive) Freiheit F\u00dcR etwas? Aber wof\u00fcr? Und k\u00f6nnen nicht sogar B\u00fcrger eines totalit\u00e4ren Staates irgendwie &#8222;frei&#8220; sein? Wenn ja, in welchem Sinn? Endet absolute Freiheit nicht in Anarchie? Was geschieht, wenn meine Freiheit die Freiheit anderer einschr\u00e4nkt? Anderer V\u00f6lker oder Generationen? Verlangt Freiheit gleiche Startchancen f\u00fcr alle? Reicht dazu gleiches&nbsp;<em>materielles<\/em>&nbsp;Verm\u00f6gen aus? Kann es gleiche Startchancen geben, wenn pers\u00f6nliche Eigenschaften (Gene, K\u00f6rperbau geistige F\u00e4higkeiten) und soziale Bez\u00fcge der Menschen (Elternhaus, Freundeskreis) gar nicht umverteilt werden k\u00f6nnen? Und ist permanente Umverteilung f\u00fcr gleiche Startchancen mit der Freiheit der Einzelnen vereinbar?<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Wollte man all diese Frage umfassend und pr\u00e4zise beantworten, k\u00f6nnte man ganze B\u00fccherw\u00e4nde f\u00fcllen. Bescheidenheit gebietet daher, die Anspr\u00fcche herunterzuschrauben. In diesem Schnellimbiss hier hat das Men\u00fc nur zwei G\u00e4nge: passive und aktive Freiheit. Die Formen der Freiheit sind getrennt angerichtet, so dass man sie bewusst wahrnehmen kann. Im Magen ist es dagegen wie in der Realit\u00e4t. Da kommen die Freiheitsformen gemischt vor.<\/p>\n\n\n\n<p>Meine Schreiberei hier war der M\u00fche wert, wenn sie Appetit auf Mehr macht und der Leser am Ende mehr Fragen zur Freiheit hat als zuvor. Denn ist nicht der Sinn all der Leserei, sich selbst wichtigere Fragen zu stellen als es der Verfasser je k\u00f6nnen w\u00fcrde? Es muss einem nicht jeder Geistesbrocken bis zum ungenie\u00dfbaren Brei vorgekaut werden! Doch Rohkost w\u00e4re zu einfach. F\u00fcr den Geschmack ist al dente besser, damit der Leser noch etwas zu kauen hat. Doch bitte nicht zu fad! Gut gew\u00fcrzt, nicht \u00fcberw\u00fcrzt. Und das Wichtigste: Die besten und frischesten Zutaten, die der Autor auf dem Markt finden konnte.<\/p>\n\n\n\n<p>Wo der Verfasser diese Zutaten gefunden hat? Das bleibt hier wie bei einem normalen Kochrezept das Geheimnis der K\u00fcche. Dieser Beitrag ist zitatfrei. Es ist alles selbst\u00e4ndig verarbeitet, nichts einfach \u00fcbernommen. \u00dcbernommen hat sich allenfalls der Verfasser bei der Auswahl des Themas und der Verarbeitung der Zutaten.<\/p>\n\n\n\n<h3><strong>1. Passive (negative) Freiheit als Freiheit von &#8230;..<\/strong><\/h3>\n\n\n\n<h4><strong>1.1 Freiheit in autorit\u00e4ren Systemen: Die Freiheit der Abh\u00e4ngigen<\/strong><\/h4>\n\n\n\n<p>Freiheit der Abh\u00e4ngigen in autorit\u00e4ren oder totalit\u00e4ren Systemen bedeutet f\u00fcr die Abh\u00e4ngigen,&nbsp;<em>\u201efrei\u201c<\/em>&nbsp;zu sein von Entscheidungszw\u00e4ngen und Verantwortung. Das verlangt nach einer Institution, die f\u00fcr die Abh\u00e4ngigen entscheidet und sie&nbsp;<em>frei<\/em>stellt von individueller Verantwortung. In den abrahamitischen Religionen (Christentum, Islam, Judentum) ist diese Institution ein allwissender und allm\u00e4chtiger Gott. Er verantwortet die Gebote und Dogmen, die das Verhalten der Gl\u00e4ubigen lenken. Die betreffen alle Lebensbereiche und sagen, was dort richtig und was falsch ist. Sie befreien vom Risiko, etwas Falsches zu tun, daher auch von Verantwortung und Haftung.<\/p>\n\n\n\n<p>Fundamentalisten verlangen die w\u00f6rtliche Auslegung der heiligen Schriften. Deutungsl\u00fccken schlie\u00dfen aber auch bei ihnen menschliche Autorit\u00e4ten mit exklusiver Gotteserkenntnis, woher sie diese auch immer beziehen. Kein Gl\u00e4ubiger muss daher noch \u00fcber Inhalt oder Sinn der Dogmen und Gebote nachdenken: Geborgenheit und Sicherheit bilden den Kern DIESER Freiheit. \u2013 Und der Preis DIESER Freiheit? Niemand darf an den Geboten und Dogmen zweifeln!<\/p>\n\n\n\n<p>Alle Menschen h\u00e4ngen von der Gnade Gottes ab. Doch dessen Wege sind &#8222;unerfindlich&#8220;. Deshalb gibt es keinen Anspruch auf diese Gnade. Ist es hoffentlich ein &#8222;guter Gott&#8220;, wird er Gnade gew\u00e4hren. Alle Gl\u00e4ubigen f\u00fchlen sich &#8222;wunderbar geborgen&#8220; und frei von Sorgen. Gott nimmt sie ihnen ab und weist ihnen den Weg zum Heil: \u201eDanke, dass ich all meine Sorgen auf dich werfen mag\u201c oder \u201eVon guten M\u00e4chten wunderbar geborgen\u201c hei\u00dft es in christlichen Kirchenliedern.&nbsp;<\/p>\n\n\n\n<p>Entweder wird den folgsamen Anh\u00e4ngern das Paradies versprochen oder es ist nur die Frage, auf wen Gottes Gnade f\u00e4llt, aus f\u00fcr Menschen \u201eunerfindlichen\u201c Gr\u00fcnden. Bei den drei abrahamitischen Weltreligionen liegt dieses Paradies im Himmel oder im Garten Eden. Eingang findet nur der Gl\u00e4ubige, der zuvor das Zeitliche gesegnet hat. Erst nach seinem Tod erwarten ihn ewige Freuden oder ewige Verdammnis.<\/p>\n\n\n\n<p>Sozialisten und Nationalsozialisten versprechen ihren gl\u00e4ubigen Aktivisten dieses Paradies schon auf Erden. In der aktuellen Politik versucht sich die chinesische Regierung in der Rolle des allwissenden und allm\u00e4chtigen Gottes. Dieser Gott ist strafend, wenn man seine Gebote nicht einh\u00e4lt, wie das Beispiel der Uiguren zeigt. Nur wer sich absolut konform verh\u00e4lt, kann sich sorgenfrei und sicher f\u00fchlen, aber keineswegs immer. Seine Entscheidungsfreiheit und seine Pflicht zur Verantwortung sind vollst\u00e4ndig seinem Gehorsam gegen\u00fcber der F\u00fchrung, seiner Passivit\u00e4t und Bequemlichkeit geopfert. Er l\u00e4sst denken! Die da oben. Daf\u00fcr spendet er ihnen von Zeit zu Zeit Lobeshymnen im Gottesdienst der Parteiversammlungen und paradiert vor ihnen mit milit\u00e4rischer Pr\u00e4zision in einer langen Prozession.<\/p>\n\n\n\n<p>Sofern er sich jeder Kritik enth\u00e4lt, ist der Abh\u00e4ngige risiko-<em>frei<\/em>, jedoch nur von Entscheidungszw\u00e4ngen und Verantwortung. F\u00fcr Kritik und Ungehorsam wird er weggesperrt, kommt in Quarant\u00e4ne, damit er andere nicht anstecken kann, so wie das fr\u00fcher mit dem Kirchenbann war,<\/p>\n\n\n\n<p>Das ist die \u201eFreiheit\u201c der Abh\u00e4ngigen.&nbsp;<em>Die haben kein Eigentum, die sind Eigentum.<\/em>&nbsp;Es hat mich immer wieder erstaunt, warum sich v\u00f6llig Abh\u00e4ngige in diesem Sinne \u201efrei\u201c f\u00fchlen k\u00f6nnen. Denn aus liberaler Sicht ist DAS keine Freiheit. Auch nicht aus Sicht der Libert\u00e4ren und Anarchisten, weil der Einzelne nicht ungestraft querdenken und querhandeln darf. Schon gar nicht wird sein Querdenken als Bereicherung und Risikosenkung f\u00fcr die Gesamtgesellschaft empfunden. Das Gegenteil ist der Fall.<\/p>\n\n\n\n<p>Trotzdem suchen wir in Alltagssituationen alle diese vermeintlich sorgenfreie Art der Freiheit, die uns Entscheidungsprobleme abnimmt: z.B. bei der Suche im Internet, beim Steuerberater oder auf der Suche nach Sicherheit und Geborgenheit im Scho\u00df einer Kirche. Doch auch, wenn diese Form der Freiheit vom \u201eEntscheidenm\u00fcssen\u201c einen gro\u00dfen Teil unseres Lebens bestimmt, k\u00f6nnen andere Formen der Freiheit unser Leben st\u00e4rker beeinflussen. Das echte Leben besteht aus einer Mischung von Freiheitsformen, die wir mehr oder weniger selbst bestimmen.&nbsp;<\/p>\n\n\n\n<h4><strong>1.2 Freiheit in anarchischen Systemen: Die Freiheit der Gesetzlosen<\/strong><\/h4>\n\n\n\n<p>Libert\u00e4re und Anarchisten verlangen absolute Freiheit von allen Entscheidungszw\u00e4ngen und von jeder R\u00fccksichtnahme auf andere, sogar die Freiheit, die Freiheit anderer einzuschr\u00e4nken. F\u00fcr sich pers\u00f6nlich, ganz allein! Kein Gebot, kein Dogma, keine staatliche Autorit\u00e4t, kein Kollektiv, kein Einzelner darf ihre individuelle Freiheit einschr\u00e4nken. Jede Fremdkontrolle ist ausgeschaltet, aber im Grunde jede Selbstkontrolle. Jeder darf tun, was er gerade will. Gebots<em>frei<\/em>! Jeder ist sein eigener Gott.<\/p>\n\n\n\n<p>Diese libert\u00e4re oder anarchische Form der Freiheit steht in krassem Gegensatz zur Freiheit der Abh\u00e4ngigen. Sie hat jedoch mit ihr gemein, dass auch diese Freiheit alle pers\u00f6nliche Verantwortung fahren l\u00e4sst. Denn Verantwortung l\u00e4sst sich nur aus einem ethischen Gebot ableiten und das wird als freiheitsbeschr\u00e4nkend abgelehnt, wie alle Gebote.&nbsp;<\/p>\n\n\n\n<p>Anarchistische Freiheit wird zum Widerspruch in sich selbst, wenn der Freie \u00fcbergriffig wird und die Freiheit anderer einschr\u00e4nkt, vor allem wenn er dadurch zur Gefahr f\u00fcr deren k\u00f6rperliche Unversehrtheit wird. Die Lust am Stalken mag gro\u00df sein, doch sie beeintr\u00e4chtigt die Freiheit der Gestalkten, bringt ihn in psychische und physische Zwangslagen. \u00c4hnliches gilt f\u00fcr die Lust am Waffentragen oder die Abneigung gegen das Maskentragen in pandemischen Zeiten. Man selbst kann sich freilich blendend dabei f\u00fchlen, wenn man auf keinen anderen R\u00fccksicht nehmen muss.<\/p>\n\n\n\n<p>Auch beim fr\u00f6hlichen Saufgelage vermittelt die anarchisch-libert\u00e4re Form der Freiheit einem selbst gute Gef\u00fchle, die allerdings bei der anschlie\u00dfenden Wirtshausschl\u00e4gerei schnell ins Gegenteil umschlagen k\u00f6nnen, wenn man an sein zerbrochenes Nasenbein denkt. Da ist man eben nicht der Einzige, der \u201efrei\u201c seine Wut auslebt.&nbsp;<\/p>\n\n\n\n<p>Diese Form der Freiheit hat im Alltagsleben oft die Funktion eines Ventils. Da wird mal richtig Dampf abgelassen. Zeitlich beschr\u00e4nkt! Denn&nbsp;<em>diese<\/em>&nbsp;Freiheit kann sich kaum jemand permanent nehmen. Dagegen w\u00fcrde sich Widerstand von au\u00dfen erheben. W\u00fcrden alle immer das tun, was im v\u00f6lligen Belieben jedes Einzelnen liegt, w\u00e4ren Gewalt und Chaos unvermeidbar.<\/p>\n\n\n\n<p>Mit dem Kategorischen Imperativ Kants ist diese grenzen- und verantwortungslose Freiheit unvereinbar. Sein Kategorischer Imperativ fordert:&nbsp;\u201eHandle so, dass die Maxime deines Willens jederzeit zugleich als Prinzip einer allgemeinen Gesetzgebung gelten k\u00f6nne.\u201c<\/p>\n\n\n\n<h4><strong>1.3 Freiheit in liberalen Systemen: Die Freiheit der Verantwortlichen<\/strong><\/h4>\n\n\n\n<p>Der Liberale erg\u00e4nzt die Freiheit DES Einzelnen im anarchischen oder libert\u00e4ren Sinn (1.2) um die Freiheit der Anderen. Dabei hat er zwei Dogmen:<\/p>\n\n\n\n<p>1. Habe kein Dogma (\u00fcber das einzig richtige Leben), in das Du andere hineinzwingst!<\/p>\n\n\n\n<p>2. Dulde kein Dogma (\u00fcber das einzig richtige Leben), in das andere Dich hineinzwingen wollen!<\/p>\n\n\n\n<p>Das sind nur Dogmen \u00fcber Dogmen. Der Liberale kennt im Unterschied zu rechten oder linken politischen Philosophien jedoch kein Dogma \u00fcber das \u201erichtige Leben\u201c aller Menschen. Er ist ein Lernender und hat daher keine konkrete Utopie \u00fcber einen erw\u00fcnschten Zustand der Gesellschaft, auf den sich die Bem\u00fchungen aller richten sollen, und f\u00fcr die er bereit w\u00e4re, mit Gewalt zu k\u00e4mpfen: in einem Putsch, einer Revolution oder einem \u201eheiligen Krieg\u201c.&nbsp;<\/p>\n\n\n\n<p>Stattdessen sucht der Liberale laufende Verbesserungen der Welt durch Vernunft, soziale Abstimmung und Einigung. Mit offenem Ausgang! Seine Begeisterung f\u00fcr Freiheit, Vernunft und Regeln f\u00fcr eine friedliche Entwicklung, die das Wissen und die Meinung aller integriert, ersetzt die Begeisterung von Extremisten f\u00fcr eine Utopie: das Paradies der Werkt\u00e4tigen, die nationale Volksgemeinschaft oder den Gottesstaat.<\/p>\n\n\n\n<p>Die Verpflichtung zur Achtung der Freiheit anderer ist der soziale Preis der liberalen Freiheit des Einzelnen im Sinne Kants. Zusammen mit dieser Verantwortung f\u00fcr die Freiheit der Anderen wird aus der Freiheit DES Einzelnen die Freiheit DER Einzelnen. Der Liberale ist daher NICHT FREI, die Freiheit anderer zu missachten, NICHT FREI, diese Freiheit nicht zu respektieren. Seine soziale Verantwortung geht \u00fcber alle Schichten der Gesellschaft, \u00fcber alle Staats- und Generationengrenzen hinweg:<\/p>\n\n\n\n<p>1. Undurchl\u00e4ssige Barrieren der Gesellschaft aufzubrechen, war der Ausgangspunkt der Ur-Liberalen im erfolgreichen Kampf gegen den Feudalismus. Doch heute sind auf dem Boden liberaler Gesellschaften neue feudale Strukturen entstanden, etwa durch Seilschaften des \u201eGeldadels\u201c oder im Bildungssystem der USA. Diese Strukturen zerst\u00f6ren die offene, liberale Gesellschaft von innen.<\/p>\n\n\n\n<p>Bei aller berechtigten Kritik an den neofeudalen Tendenzen in liberalen Gesellschaften: Totalit\u00e4re Gesellschaften lassen eine offene Gesellschaft erst gar nicht entstehen. Ihr Personenkult, ihre Vetternwirtschaft und die Abschottung ihrer politischen Elite stehen f\u00fcr einen institutionalisierten Neofeudalismus ungleich gr\u00f6\u00dferen Ausma\u00dfes, ob in Nordkorea, China, der T\u00fcrkei oder in Belarus.<\/p>\n\n\n\n<p>Die Kritik an neofeudalen Tendenzen in liberalen Gesellschaften ignoriert das meist. Sie vergleicht die&nbsp;<em>perfekteScheinwelt<\/em>&nbsp;der sozialistischen Ideologie&nbsp;<em>mit<\/em>&nbsp;der&nbsp;<em>unperfekten Realit\u00e4t<\/em>&nbsp;liberaler Gesellschaften, nicht die realen Systeme \u201eliberale und sozialistische Gesellschaft\u201c. Im direkten Vergleich der realen Systeme f\u00e4llt das Urteil \u00fcber neofeudale Tendenzen trotz aller M\u00e4ngel deutlich zugunsten der liberalen Gesellschaften aus. Beim direkten Vergleich der Ideologien w\u00fcrde man feststellen, dass auch die liberale Ideologie keinen Neo-Feudalismus kennt. Wie sollte es nach dem erfolgreichen Kampf gegen den Feudalismus anders sein!<\/p>\n\n\n\n<p>2. Nationalliberale haben urspr\u00fcnglich grenz\u00fcberschreitendes Denken gezeigt, als sie halfen, die deutsche Kleinstaaterei zu \u00fcberwinden. H\u00e4tten sie auf diesem Weg weitgemacht, w\u00e4ren sie heute Bef\u00fcrworter der EU. Als deren Gegner aber sind sie aus der Zeit gefallen. Ihr \u201eMy Country First!\u201c beschr\u00e4nkt die liberale Verantwortung auf die Landsleute. In einer globalen Welt verletzt dies das Prinzip Kants. Nationalliberale sind daher halbherzige Liberale mit einem Handicap.<\/p>\n\n\n\n<p>3. Mit der generationen\u00fcberschreitenden Verantwortung f\u00fcr die Freiheit anderer, ist man beim Umwelt- und Klimaschutz. Liberale L\u00f6sungen im Umweltschutz sind nicht in erster Linie Ver- und Gebote, Strafsteuern oder Subventionen, sondern Marktl\u00f6sungen. Die Rede vom \u201eUmwelt- und Klimakiller Markt\u201c ist v\u00f6llig abwegig, weil der Markt bei freien Umweltg\u00fctern gerade NICHT zum Einsatz kam und kommt. Der angebliche Klimakiller hat hier ein perfektes Alibi. Das beweist auch die h\u00f6here Verschmutzung der Umwelt und der schlechtere Klimaschutz in nichtliberalen Gesellschaften mit planwirtschaftlichem System.<\/p>\n\n\n\n<p>Mit seiner umfassenden Verantwortung f\u00fcr die Freiheit anderer, ist der Liberale gerade kein &#8222;verantwortungsloser Geselle&#8220;. Das sind eher seine Ankl\u00e4ger, die sich von Verantwortung befreien: als gehorsame Untertanen gott\u00e4hnlicher Potentaten, als Anarchisten oder als \u201equasi-Libert\u00e4re\u201c Neofeudale im liberalen System, denen die eigene Freiheit weit \u00fcber die Freiheit der anderen geht.<\/p>\n\n\n\n<p>Im Gefolge des Kategorischen Imperativs Kants hat gerade der Liberale kein egoistisches Menschenbild. Dies aber wird ihm vorgeworfen: durch Verwechselung mit den Libert\u00e4ren, aber oft auch im Zusammenhang mit dem &#8222;homo oeconomicus&#8220;, der DAS Leitbild des Liberalismus sein soll. Der \u201ehomo oeconomicus\u201c ist aber nur eine Kunstfigur f\u00fcr \u00f6konomische Modelle, ein Avatar, der im Modell strikt rational, v\u00f6llig mechanisch und vollkommen vorhersehbar allein auf \u00f6konomische Anreize reagiert. \u201eStrikt rational\u201c ist jedoch nicht zugleich egoistisch, denn \u201estrikt rational\u201c kann oder sollte man auch mit altruistischen Motiven handeln, um z.B. als Stiftung Verschwendung zu vermeiden und m\u00f6glichst viele Mittel dem altruistischen Stiftungszweck zuzuf\u00fchren.<\/p>\n\n\n\n<p>Aus Gr\u00fcnden der Prognosesicherheit im Modell ist die Kunstfigur &#8222;homo oeconomicus&#8220; absolut&nbsp;<em>unfrei<\/em>konzipiert. Das gilt ebenso f\u00fcr die Kunstfigur des Behavioristischen Menschen oder f\u00fcr den homo deus, der laut Harari aus einem Algorithmus &#8222;<em>besteht<\/em>&#8222;. Denn das Verhalten frei entscheidender Menschen ist nicht exakt prognostizierbar. Das ist der wesentliche Grund, warum man dem&nbsp;<em>Menschen als Modellfigur<\/em>&nbsp;seine Freiheit nimmt. Als Menschen- und Leitbild einer realen Philosophie der Freiheit kann ein v\u00f6llig unfreier &#8222;homo oeconomicus\u201c niemals geeignet sein. Daher l\u00e4sst sich an ihm auch keine Kritik des Liberalismus festmachen.<\/p>\n\n\n\n<p>W\u00e4ren diese unfreien Modellfiguren echte Menschen, lie\u00dfe sich bezweifeln, ob der Mensch \u00fcberhaupt \u201efrei\u201c sein kann. Und wer unfrei ist, kann keine Verantwortung tragen und haftet zu Unrecht f\u00fcr das, was er tut. Denn verantwortlich sind seine Gene (sehr gern von rechten Extremisten benutzt), die gesellschaftlichen Verh\u00e4ltnisse (da sind wir bei den Linken) oder die umfassende Kenntnis, Kontrolle und Steuerung durch moderne Kommunikationsmedien (das ist der homo deus von Harrari, wohl am weitesten realisiert in China). Auch Kindersch\u00e4nder sind dann v\u00f6llig fremdgesteuert und nicht pers\u00f6nlich verantwortlich. Wer die Ursache in ihrer Genetik sieht, kann sie nur wegsperren oder ausmerzen. Wer die gesellschaftlichen Verh\u00e4ltnisse verantwortlich macht, wird zeigen m\u00fcssen, dass es unter ge\u00e4nderten Verh\u00e4ltnissen gar nicht erst zu Verbrechen kommt. Das f\u00fchrt zu den Vertuschungsaktionen \u00fcber Verbrechen in den sozialistischen Staaten, weil nicht sein kann, was nicht sein darf. Bei aller Einschr\u00e4nkung unserer Freiheit, glaubt der Liberale jedoch daran, dass es noch einen Rest pers\u00f6nlicher Freiheit und Verantwortung gibt. Und die Regenschirme von Hongkong schreien danach!<\/p>\n\n\n\n<h3><strong>2. Aktive (positive) Freiheit als Freiheit zu &#8230;<\/strong><\/h3>\n\n\n\n<p>Im liberalen System beschreibt&nbsp;<em>aktive<\/em>&nbsp;Freiheit die M\u00f6glichkeiten zur sozialen Teilnahme der Menschen an Kultur, Politik und Wirtschaft. Im totalit\u00e4ren System gibt es keine aktive Freiheit. Hier wird soziale Teilnahme nicht erm\u00f6glicht, die Teilnahme wird verlangt oder verboten. Und im anarchischen System&nbsp;<em>darf<\/em>&nbsp;es keine institutionelle Unterst\u00fctzung f\u00fcr aktive Freiheit geben. Aktive Freiheit schlie\u00dft staatliche Regulierung ein und die widerspricht der anarchistischen oder libert\u00e4ren Ideologie.<\/p>\n\n\n\n<p>Ohne ein Minimum an Mitteln ist aktive Freiheit dem Einzelnen unm\u00f6glich. Das sind jedoch nicht nur materielle Mittel, wie Materialisten einseitig betonen.&nbsp;Heute&nbsp;sind immaterielle Faktoren, wie Bildung, Gesundheit und der Zugang zu Informationen mindestens genauso wichtig wie die materielle Ausstattung.<\/p>\n\n\n\n<p>Im Unterschied zu Sozialisten blicken Liberale nicht auf die Verteilung von Ergebnissen, sondern auf die Startchancen. W\u00fcrde man stetig versuchen, die materiellen Startchancen aller Menschen gleichzumachen, m\u00fcsste der Staat permanent umverteilen. Denn je nach Neigung und Unterschieden in pers\u00f6nlichen und sozialen F\u00e4higkeiten und Fertigkeiten ergeben sich selbst bei gleicher materieller Anfangsausstattung laufend Unterschiede in den Ergebnissen menschlichen Handelns, unabh\u00e4ngig vom Wirtschaftssystem. Anders w\u00e4re es, wenn eine Gleich- oder Umverteilung individueller Neigungen, F\u00e4higkeiten, Fertigkeiten und k\u00f6rperlicher sowie geistiger Behinderungen m\u00f6glich w\u00e4re. Die ist aber nicht einmal denkbar.<\/p>\n\n\n\n<p>Sozialistische Materialisten ignorieren diese Notwendigkeit der Umverteilung immaterieller Startchancen. W\u00fcrde die Verteilung des materiellen Verm\u00f6gens durch umverteilende Staatseingriffe dauernd auf &#8222;Anfang&#8220; gestellt, unabh\u00e4ngig davon, ob jemand sein Geld vers\u00e4uft oder sich anstrengt, zerst\u00f6rt man jedoch sowohl passive und als auch aktive Freiheit, weil man die Ergebnisse des Gebrauchs dieser Freiheiten laufend vernichtet. Wer aber den Gebrauch der Freiheit sanktioniert, sanktioniert auch die Freiheit. Und selbst wenn auf diese Weise materielle Gleichheit kurzfristig hergestellt w\u00fcrde, bleiben individuelle Ungleichheiten: aus Genetik und Erziehung. Eine Gleichverteilung all dieser Eigenschaften im Sinne gleicher Startchancen ist unm\u00f6glich.<\/p>\n\n\n\n<p>Immer wieder richten Sozialisten die Diskussion dennoch allein auf die materielle Basis. Doch die Liste der reichsten Menschen wird heute nicht von Personen angef\u00fchrt, die bereits von Kindheit an materiell extrem gut gestellt waren. Das relativiert die Bedeutung materieller Gleichheit f\u00fcr die Gleichheit der Startchancen. Unbedeutend wird sie dadurch nicht. Denn ohne materielle Grundsicherung ist aktive Freiheit unm\u00f6glich.<\/p>\n\n\n\n<p>Ein rein materialistischer Ansatz missachtet alle immateriellen Quellen der Ungleichheit. Aktive Freiheit im liberalen Sinn erkennt dagegen die Unm\u00f6glichkeit absoluter Gleichheit aller Startchancen. Gleichwohl muss politisch permanent daran gearbeitet werden, um die aktive Teilhabe aller Menschen zu erm\u00f6glichen. Das schlie\u00dft zwar eine materielle Grundsicherung ein,&nbsp;heute&nbsp;entscheiden aber vor allem den Zugang zu Bildung und Informationen, aber auch zu medizinischer Versorgung. Hinzu kommen Einzelfragen um regionale Unterschiede oder solche um Geschlecht, k\u00f6rperliche und geistige Einschr\u00e4nkungen oder Herkunft.&nbsp;<\/p>\n\n\n\n<p><em>Gleichbehandlung<\/em>&nbsp;w\u00e4re hier&nbsp;<em>gegen<\/em>&nbsp;den Sinn aktiver Freiheit. Denn dabei geht es um die F\u00f6rderung Benachteiligter und deren Bef\u00e4higung zu aktiver Teilnahme. Dabei werden z.B. durch Rampen f\u00fcr Rollstuhlfahrer oder Markierungen f\u00fcr Blinde Nachteile f\u00fcr Unversehrte in Kauf genommen.<\/p>\n\n\n\n<p>Wer als Liberaler die&nbsp;<em>aktive<\/em>&nbsp;Freiheit neben der passiven besonders betont, z\u00e4hlt zu den &#8222;Sozial-Liberalen&#8220;. Hier geht&nbsp;heute&nbsp;ein Riss durch die Liberalen, die sich au\u00dfer bei der extremen Rechten und Linken in allen politischen Parteien finden: bei den Realos der Gr\u00fcnen ebenso wie bei CDU und SPD. Bei der FDP, der Partei, die den Liberalismus im Schilde f\u00fchrt, wurde mit den Freiburger Thesen die aktive Freiheit betont. Seitdem hat sich deren Mehrheit weitgehend auf die passive Freiheit zur\u00fcckgezogen.<\/p>\n\n\n\n<h3><strong>3. Meine Freiheit<\/strong><\/h3>\n\n\n\n<p>Meine Freiheit ist nicht, frei zu sein, wie die Libert\u00e4ren es sind und die Anarchisten: Frei zu sein, Waffen zu tragen; frei zu sein, sich bei pandemischen Viren nicht impfen zu lassen; frei zu sein, im Restaurant in Anwesenheit anderer zu rauchen oder in enger Gegenwart anderer keine Corona-Maske zu tragen. Solche Freiheiten sind egoistische libert\u00e4re Freiheiten, die sich zur Egomanie auswachsen k\u00f6nnen. Sie gehen oft zu Lasten der Freiheit anderer, ihrer Gesundheit und ihrer k\u00f6rperlichen Unversehrtheit.&nbsp;<\/p>\n\n\n\n<p>N\u00e4hmen sich alle Menschen diese Freiheit, w\u00fcrden wir in Streit und Chaos versinken. Raucht der eine in seiner Anwesenheit, zieht der andere seine Waffe und nimmt selbst sich die Freiheit, den l\u00e4stigen Raucher zu erschie\u00dfen. Kein Gesetz, keine Ethik und keine Moral hindern ihn daran. Allein die Gegengewalt anderer k\u00f6nnte ihn bremsen und ihn verantwortlich machen: So begr\u00fcndet die Waffenlobby in den USA das allgemeine Tragen von Waffen.<\/p>\n\n\n\n<p>Meine Freiheit ist auch nicht, frei zu sein, wie Menschen, die sich einem Dogma oder einer Institution unterwerfen, um sich von Entscheidungszw\u00e4ngen zu befreien und vor pers\u00f6nlicher Verantwortung zu dr\u00fccken. Sicherheit, Geborgenheit und Bequemlichkeit sind die Verlockungen dieser Freiheit der Abh\u00e4ngigen. Im Internet unterwerfen sich ihr t\u00e4glich unz\u00e4hlige Menschen und begr\u00fcnden damit die Macht von Facebook, Google und Co., vor allem aus Bequemlichkeit.<\/p>\n\n\n\n<p>Doch Sicherheit, Geborgenheit und Bequemlichkeit sind tr\u00fcgerisch. Denn wer auf diese Weise frei ist, der liefert sich aus, macht sich abh\u00e4ngig vom Wohlwollen und der Gnade derjenigen, denen er seine Entscheidungen, seine Kontrolle und seine Verantwortung abtritt. Man muss gar kein Kontrollfreak sein, um diese Freiheit als wackelig zu empfinden. Jederzeit kann sie von Diktatoren oder Googles dieser Welt zum eigenen Nachteil ausgenutzt werden. Viele dieser menschlichen G\u00f6tzen haben die Abh\u00e4ngigen selbst zu ihren G\u00f6tzen gemacht. Und sie feiern t\u00e4glich G\u00f6tzendienst vor den Symbolen ihrer Macht. Das wird schon in der Jugend ge\u00fcbt: vor Fanpostern, Autogrammen und Merchandising-Ikonen von Teenie-Idolen. Aber ist das frei?<\/p>\n\n\n\n<p>Meine Freiheit ist, frei zu sein wie ein Liberaler. Frei und dennoch gebunden in der Verantwortung f\u00fcr die Freiheit anderer, wo immer die auch sind: meine Nachbarn, meine Landleute, die Menschen jenseits der Grenzen und die meiner Enkel. Und meine Freiheit ist nicht nur eine&nbsp;<em>passive&nbsp;<\/em>des Verhinderns (von unn\u00f6tiger Einmischung des Staates, von privaten Institutionen, Kollektiven und Individuen), sondern auch eine&nbsp;<em>aktive<\/em>des Erm\u00f6glichens (der Teilhabe aller Menschen an der Gestaltung von Kultur, Politik und Wirtschaft).&nbsp;<\/p>\n\n\n\n<p>Dabei geht es mir nicht wie den \u201eGutmenschen\u201c vor allem darum, mein eigenes Gewissen zu entlasten mit einer Gesinnungsethik, die ja nur Gutes&nbsp;<em>will<\/em>. Es geht um die&nbsp;<em>Folgen&nbsp;<\/em>meines Tuns, so weit wie ich sie erkennen kann, auch um die Folgen der Folgen. Das ist umfassende Verantwortung als Richtschnur meines Handelns und es ist viel mehr als der Versuch, mit guter Gesinnung das eigene Gewissen zu entlasten.<\/p>\n\n\n\n<p>F\u00fcr manche mag das eine zu sehr eingeschr\u00e4nkte Freiheit sein. Und eine Freiheit, die einen dauernd \u00fcberfordert, weil man ihren Anspr\u00fcchen nie gerecht werden kann. Und doch ist das&nbsp;<em>meine<\/em>&nbsp;Freiheit. \u2013 Ob ich sie auch lebe?&nbsp;<em>Keinen Tag lang<\/em>. Denn sie \u00fcberfordert mich laufend und ich bin nur ein Mensch mit bescheidenen F\u00e4higkeiten. Doch sie gibt mir Leitlinie und Orientierung. Sie l\u00e4sst mich meine Entscheidungskraft und Verantwortung behalten. Kurz: Sie macht mich zum m\u00fcndigen B\u00fcrger und nicht zum M\u00fcndel anderer oder zur Marionette eines Systems.<\/p>\n\n\n\n<p>Dazu geh\u00f6rt das, was mir die aktive Teilnahme an Kultur, Politik und Wirtschaft m\u00f6glich gemacht hat, vor allem meine schulische und universit\u00e4re Ausbildung. Die habe ich durch eigenst\u00e4ndige Bildung erg\u00e4nzt oder ersetzt und tue es heute noch laufend. Aktive Freiheit verlangt vor allem den Ausgleich von Handicaps. Da habe ich mein wesentliches Handicap, meine Kindheit und Jugend, lange hinter mir gelassen. Andere brauchen da mehr Unterst\u00fctzung. Ich bin daf\u00fcr, sie ihnen zu geben. Auch von Staats wegen.&nbsp;<\/p>\n\n\n\n<p>Streng genommen lebe ich selbst&nbsp;<em>alle<\/em>&nbsp;genannten Freiheiten, aber ich liebe nicht alle gleich. Politische und religi\u00f6se Fundamentalisten mit \u00fcbergriffigen Ideologien entscheiden sich f\u00fcr die totalit\u00e4re Form. Und auch ich lasse mir ab und zu Entscheidungen und Verantwortung abnehmen und mache mich abh\u00e4ngig, etwa von meinem Steuerberater. Und sollte ich bei einer Party mal ausflippen und keinen anderen mehr im Blick haben, habe ich sicher einen Schluck zu viel aus der Anarcho-Pulle mit dem Etikett \u201eLibert\u00e4r\u201c getrunken. Doch ich entferne mich nie allzu weit von meiner Lieblings-Freiheit. Und das ist nun mal die liberale. Dahin komme ich immer wieder zur\u00fcck.<\/p>\n\n\n\n<p>Doch ich muss einsehen: Meine Freiheit ist die unbeliebteste aller Freiheiten. Das habe ich in der Corona-Krise gemerkt. Da sind viele Deutsche vor allem wegen der anarchischen Masken-Freiheit in die Niederlande gefahren, weil sie der Bevormundung durch die Maskenpflicht in Deutschland entgehen wollten. Diese Freiheit ohne gef\u00fchlte Verantwortung ist im Zweifel die Nummer eins der Rangordnung, selbst wenn sie Risiken f\u00fcr andere birgt. Die Leute wollen individuelle Freiheit, sind aber nicht bereit, den Preis pers\u00f6nlicher Verantwortung und Haftung daf\u00fcr zu zahlen.<\/p>\n\n\n\n<p>Ohne Maskenpflicht setzt in Deutschland oder in den Niederlanden kaum jemand eine Maske auf. Wo k\u00e4men wir denn hin, wenn man aus Verantwortung f\u00fcr die Freiheit und Gesundheit anderer&nbsp;<em>freiwillig<\/em>&nbsp;eine Maske tr\u00fcge!? Doch ich tue das.&nbsp;<\/p>\n\n\n\n<p>Ich war mit meiner Maske in Deutschland fremd, als es noch keine Maskenpflicht gab, ich bin das jetzt in den Niederlanden, weil ich sie freiwillig trage, wenn ich anderen zu nahe komme. Und die Leute? Sie machen einen gro\u00dfen Bogen um mich, wenn ich&nbsp;<em>ohne Maskenpflicht<\/em>&nbsp;eine Maske trage und laufen lieber nahe an Leuten vorbei, die keine Maske tragen. Das ist nicht meine Logik, sondern die der Leute. Denn in&nbsp;<em>meiner<\/em>&nbsp;N\u00e4he w\u00e4ren sie sicherer.<\/p>\n\n\n\n<p>Das Verhalten der Leute \u00e4ndert sich nur, wenn es eine Maskenpflicht f\u00fcr alle gibt. Dann f\u00fchlen sie sich in der diktatorischen \u201eFreiheit\u201c gut aufgehoben, jedenfalls besser, als wenn sie aus eigener Verantwortung eine Maske tragen. So kommt diese \u201eFreiheit\u201c, die ihnen das Entscheidenm\u00fcssen erspart, auf Rang zwei der beliebtesten Freiheiten. Ganz hinten rangiert deshalb die Freiheit, die sich an pers\u00f6nliche Verantwortung und Haftung koppelt. Dieser Preis der Freiheit ist den meisten zu hoch. Oder sie sehen sich nicht in der Lage, aus eigenem Antrieb verantwortungsvoll zu handeln, vor allem nicht unter verantwortungslosen Anarchos, die auf dicke Hose machen: Schaut her, wie frei ich bin! Ohne Maske! Das k\u00f6nnt Ihr auch! Und dann lassen sie ihre Maske fallen.<\/p>\n\n\n\n<p>In einem solchen Umfeld aus eigener Verantwortung eine Maske zu tragen, \u00fcberfordert offenbar viele. Es bleibt dennoch jedem \u00fcberlassen, trotz fehlender Maskenpflicht in eigener Verantwortung eine Maske zu tragen. Das ist die Freiheit m\u00fcndiger Menschen und deshalb bleibt sie meine Lieblings-Freiheit. Nur wer hier gegen den Strom schwimmt, kann zur Quelle meiner Lieblings-Freiheit finden.<\/p>\n\n\n\n<p>Und was ist Deine Lieblings-Freiheit?<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong>Ich bin so frei<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Despotische Freiheit<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\">Ich bin so frei, ich muss nicht denken,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Das m\u00fcssen andere f\u00fcr mich tun.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Ich muss mir nicht mein Hirn verrenken,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Bei mir kann der Verstand ausruh\u2018n.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Der f\u00fcr mich denkt, ist mein Diktator.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Wer f\u00fcr mich denkt, der ist mein Gott.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Er schreibt mir alles ganz genau vor,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Wenn ich\u2019s nicht tue, droht\u2019s Schafott.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\">Doch wenn ich\u2019s tue, bin ich \u201efrei\u201c,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Ich muss mich nie entscheiden,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Ist nie Verantwortung dabei,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Die kann ich immer meiden.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Und frei von dieser Last zu sein,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Das ist ein sch\u00f6nes Leben,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Da f\u00fchl ich niemals mich allein.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Was kann es Sch\u00f6n\u2019res geben!<\/p>\n\n\n\n<p class=\"has-text-align-center\">Zudem verhei\u00dft man bei uns allen<\/p>\n\n\n\n<p class=\"has-text-align-center\">\u2018S Schlaraffenland, das Paradies,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Das MUSS doch allen auch gefallen,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Wem\u2019s nicht gef\u00e4llt, ja der ist mies.<\/p>\n\n\n\n<p><span style=\"color:#ffffff\" class=\"tadv-color\">lll<\/span><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Anarchisch-libert\u00e4re Freiheit<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\">Was Du \u201efrei\u201c nennst, nenn ich \u201eversklavt\u201c,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Dir ist ja nichts erlaubt.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Der ist schon ziemlich unbedarft,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Der Deinen Unsinn glaubt.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Frei ist&nbsp;<em>nur<\/em>, wer ohne Zwang,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Stets das tun kann, was er gern mag.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Er folgt allein dem eig\u2019nen Drang<\/p>\n\n\n\n<p class=\"has-text-align-center\">Den lieben langen Tag.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Er tut alleine, was er will,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Was immer auch die and\u2019ren wollen.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Regeln und Pflichten schweigen still,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Es gibt kein M\u00fcssen und kein Sollen.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Er darf nach Lust und Laune paffen,<\/p>\n\n\n\n<p class=\"has-text-align-center\">\u2018Ne Waffe tragen, Maske nicht,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Ihn st\u00f6ren nicht die anderen Affen<\/p>\n\n\n\n<p class=\"has-text-align-center\">Und kein Gesetz und kein Gericht.<\/p>\n\n\n\n<p><span style=\"color:#ffffff\" class=\"tadv-color\">llll<\/span><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Liberale Freiheit<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\">Das ist Wunschdenken, es ist krank,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Da fehlt mir der Gedanken Strenge,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Ich riech\u2018 der Anarchie Gestank,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Der Zwang entsteht doch durch die Menge.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Was einer tut, was einer macht,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Wirkt sich auf and\u2019re aus,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Bringt viele Zw\u00e4nge, leis und sacht,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Treibt&nbsp;<em>diese<\/em>&nbsp;Freiheit aus.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Pisst einer wem an seine Karre,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Schr\u00e4nkt seine Freiheit ein,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Dann z\u00fcckt der andere seine Knarre<\/p>\n\n\n\n<p class=\"has-text-align-center\">Und schie\u00dft ihm in sein Bein.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Wem Freiheit and\u2019rer nicht egal,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Wer sie im Auge hat,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Der nennt mit Recht sich liberal,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Hat dadurch Pflichten satt.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Auf Nachbarn, Enkel muss er achten,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Da bleibt ihm keine Wahl.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Weil sie nach&nbsp;<em>ihrer<\/em>&nbsp;Freiheit trachten,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Ja liberal ist eine Qual.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Die Grenzen seiner eig\u2019nen Freiheit<\/p>\n\n\n\n<p class=\"has-text-align-center\">Die definiert man st\u00e4ndig neu.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Wer sich nicht wandelt mit der Zeit,<\/p>\n\n\n\n<p class=\"has-text-align-center\">bleibt nicht dem Liberalen treu.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Treu der Verantwortung f\u00fcr alles,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Was er auch macht, was er auch tut.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Er haftet&nbsp;<em>selbst<\/em>&nbsp;im Fall des Falles,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Da braucht er Kraft, da braucht er Mut.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Und rechte und auch linke Boten<\/p>\n\n\n\n<p class=\"has-text-align-center\">Totalit\u00e4rer Ideologie<\/p>\n\n\n\n<p class=\"has-text-align-center\">Die hau\u2019n ihm st\u00e4ndig auf die Pfoten<\/p>\n\n\n\n<p class=\"has-text-align-center\">Verstehen seine Freiheit nie.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Sie gaukeln vor ein Paradies,<\/p>\n\n\n\n<p class=\"has-text-align-center\">In das sie alle zwingen,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Zu&nbsp;<em>deren<\/em>&nbsp;Wohl \u2013&nbsp;<em>sie<\/em>&nbsp;kennen dies \u2013<\/p>\n\n\n\n<p class=\"has-text-align-center\">Weil&nbsp;<em>sie allein<\/em>&nbsp;die Wahrheit bringen.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Der Liberale ist bescheiden,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Er glaubt nicht an das Heilsgeschw\u00e4tz,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Drum m\u00f6gen viele ihn nicht leiden,<\/p>\n\n\n\n<p class=\"has-text-align-center\">F\u00fcr sie ist ihre \u201eReligion\u201c Gesetz.<\/p>\n\n\n\n<p class=\"has-text-align-center\">W\u00e4r\u2018 Fu\u00dfball wirklich unser Leben,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Hassten das Spiel sie wie die Pest.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Ergebnisoffen darf\u2018s nicht geben,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Der Staat legt das Ergebnis fest.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Des Liberalen Denken zielt dagegen<\/p>\n\n\n\n<p class=\"has-text-align-center\">Auf faire Regeln f\u00fcr das Spiel,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Kaum Korrekturen gibt\u2019s deswegen,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Schie\u00dft einer mal ein Tor zu viel.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\">Ein fairer Wettkampf ist das Ziel,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Wo jeder kann gewinnen,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Da ist auch etwas Gl\u00fcck im Spiel,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Doch das kann schnell zerrinnen.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Doch wer\u2018s Ergebnis kennen will,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Bevor ein Spiel gelaufen ist,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Der ignoriert die Regeln still,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Manipuliert mit List.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Als Liberaler muss man akzeptieren,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Selbst wenn die anderen oft gew\u00f6nnen.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Da wird man dann auch mal verlieren,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Und es den anderen g\u00f6nnen.<\/p>\n\n\n<p style=\"text-align: left;\"><span style=\"font-size: =;\"><a href=\"http:\/\/www.neschle.de\/download-manager.php?id=220\">PDF-Datei<\/a><span style=\"font-size: small;\"><br \/>This post was downloaded by  332 people until now.<\/span><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Meine Freiheit, Deine Freiheit \u2013 Die Freiheit, \u201eFreiheit\u201c (nicht) zu verstehen Freiheit, die ich meine (Max von Schenkendorf, oft benutzt, oft missbraucht) Vorbemerkung Liberal sein, hei\u00dft f\u00fcr Freiheit sein.&nbsp;Aber f\u00fcr welche Freiheit? F\u00fcr meine Freiheit, f\u00fcr Deine Freiheit? F\u00fcr die Freiheit aller anderen? \u00dcber alle Grenzen hinaus? Was ist mit der Freiheit meiner Enkel und &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/neschle.de\/index.php\/blog\/leon-neschle-84\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eLeon Neschle 84\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,6],"tags":[108,107,14,11],"_links":{"self":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/1232"}],"collection":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/comments?post=1232"}],"version-history":[{"count":10,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/1232\/revisions"}],"predecessor-version":[{"id":1248,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/posts\/1232\/revisions\/1248"}],"wp:attachment":[{"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/media?parent=1232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/categories?post=1232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neschle.de\/index.php\/wp-json\/wp\/v2\/tags?post=1232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}